{"id":165734,"date":"2021-07-28T08:00:36","date_gmt":"2021-07-28T06:00:36","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=165734"},"modified":"2024-08-07T14:38:43","modified_gmt":"2024-08-07T12:38:43","slug":"ripara-tesla-700-euro-officina","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/curiosita\/ripara-tesla-700-euro-officina\/165734\/","title":{"rendered":"Ripara da solo una Tesla con 700 euro, in officina ne volevano 16.000"},"content":{"rendered":"<p>Oltre a essere auto che solo in pochi possono permettersi, le Tesla hanno anche un costo di manutenzione molto elevato. A confermarlo \u00e8 quanto accaduto all&#8217;ingegnere del Radio City Music Hall di New York Donald Bone, jl quale, dopo aver riscontrato dei problemi con la sua Model 3, <strong>ha ricevuto un conto salatissimo<\/strong> da parte di un centro di riparazione ufficiale della Casa americana.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/curiosita\/ripara-tesla-700-euro-officina\/165734\/#Preventivo_spaventoso\" title=\"Preventivo spaventoso\">Preventivo spaventoso<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/curiosita\/ripara-tesla-700-euro-officina\/165734\/#Il_meccanico_del_miracolo\" title=\"Il meccanico del &#8220;miracolo&#8221;\">Il meccanico del &#8220;miracolo&#8221;<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Preventivo_spaventoso\">Preventivo spaventoso<\/span><\/h2>\n<p>Il nuovo gioiellino dell&#8217;uomo aveva infatti riscontrato delle criticit\u00e0 al sistema di raffreddamento della batteria causato, molto probabilmente, dalla presenza di detriti sulla strada. Come se ci\u00f2 fosse poco, la <a href=\"https:\/\/www.virgilio.it\/motori\/auto\/svelata-nuova-tesla-model-3-prezzo-resta-invariato\/197106\/\">Model 3<\/a>, la vettura elettrica pi\u00f9 venduta al mondo, ha successivamente subito ulteriori danni provocanti una copiosa uscita del liquido refrigerante motivo di ansia e preoccupazione per il facoltoso proprietario. Raggiunto il centro e controllata la macchina, la batosta finale, il colpo di grazia mai aspettato da Bone: <strong>danni per 16mila dollari<\/strong> che la sua polizza assicurativa evitava di coprire.<\/p>\n<p>Una vera e propria gatta da pelare, ciononostante l&#8217;ingegnere ha perseverato e, anzich\u00e9 cedere alle pretese degli specialisti, ha tenuto botta. I danni alla sua Model 3 (reduce da un richiamo della compagnia a stelle e strisce) sembravano facilmente risolvibili, bench\u00e9 da parte del marchio erano quantificati in una cifra monstre. L&#8217;ingegno di Bone, presosi tempo prima di lasciare il veicolo nelle mani dei meccanici, \u00e8 andato oltre, fino a trovare un nido sicuro sul web.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Il_meccanico_del_miracolo\">Il meccanico del &#8220;miracolo&#8221;<\/span><\/h2>\n<p>I tutorial in rete raccolgono spesso l&#8217;interesse generale degli utenti poich\u00e9 danno modo di eseguire operazioni altrimenti fuori portata. Quando si tratta di maneggiare una vettura, a onor del vero, sarebbe opportuno disporre di una manualit\u00e0 adeguata, o, perlomeno, eseguire le procedure con puntiglio, altrimenti invece di risolversi, i problemi rischierebbero di aggravarsi e allora il professionista interpellato sarebbe nella posizione di calcare la mano in fattura. Piuttosto di lasciarsi tradire dalla fretta, e consentirgli di avere il coltello dalla parte del manico, tanto vale fare un bel respiro e studiarsi alla lettera le istruzioni reperibili nei meandri di internet.<\/p>\n<p>E proprio su internet Donald ha trovato i migliori consigli sul da farsi, contenuti in un video su YouTube riguardante una soluzione vantaggiosa sotto il piano economico rispetto alla somma richiesto del centro di riparazione ufficiale Tesla. Imbattutosi sul canale Electrified Garage, un\u2019officina privata del New Hampshire gestita dal noto youtuber e appassionato di automobili Rich Benoit seguito da pi\u00f9 di 1,1 milioni di iscritti, Bone \u00e8 riuscito a riparare il suo bolide <strong>spendendo soltanto 700 euro<\/strong>.<\/p>\n<p>Ma perch\u00e9 una cos\u00ec netta differenza tra la tariffa proposta da <a href=\"https:\/\/www.virgilio.it\/motori\/auto\/tesla-motors-storia-curiosita-casa-americana\/78503\/\" target=\"_blank\" rel=\"noopener\" data-doctype=\"\">Tesla<\/a> e quella &#8220;risolutiva&#8221; del web? Bone, seguendo i consigli, si \u00e8 affidato a un meccanico, il quale non ha fatto altro che tagliare l&#8217;estremit\u00e0 del componente danneggiato e riavviarla alla base, mediante un comune raccordo in ottone. Chad Hrencecin, il meccanico del &#8220;miracolo&#8221;, ha imputato alle grandi aziende di non essere propense a sostituire piccoli elementi per questione economiche, ma a <strong>disporre l&#8217;intero cambio dell&#8217;unit\u00e0<\/strong> che, come Bone stava per riscontrare a suo discapito, il pi\u00f9 delle volte si aggirano su cifre di gran lunga superiori.<\/p>\n","protected":false},"excerpt":{"rendered":"Davanti alla richiesta monstre di Tesla, Bone ha consultato il web e trovato un video che gli ha permesso di risparmiare per riparare la Model 3","protected":false},"author":183220661,"featured_media":234411,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420890037],"tags":[420890830,420890888],"coauthors":[420891145,420891347],"class_list":{"0":"post-165734","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-curiosita","8":"tag-manutenzione-auto","9":"tag-tesla","10":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2021\/07\/Tesla-riparazione.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/165734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220661"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=165734"}],"version-history":[{"count":6,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/165734\/revisions"}],"predecessor-version":[{"id":237584,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/165734\/revisions\/237584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/234411"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=165734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=165734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=165734"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=165734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}