{"id":169511,"date":"2021-11-09T17:42:59","date_gmt":"2021-11-09T16:42:59","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=169511"},"modified":"2023-12-14T14:19:50","modified_gmt":"2023-12-14T13:19:50","slug":"cose-il-certificato-di-proprieta-auto-e-a-cosa-serve","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/info-utili\/cose-il-certificato-di-proprieta-auto-e-a-cosa-serve\/169511\/","title":{"rendered":"Cos&#8217;\u00e8 il certificato di propriet\u00e0 auto e a cosa serve"},"content":{"rendered":"<p>Tutti coloro che possiedono un\u2019auto sanno benissimo che ci sono dei documenti molto importanti da conservare e altri che vanno sempre portati con s\u00e9, fondamentali in caso di controlli da parte delle Forze dell\u2019Ordine durante posti di blocco su strada. Oggi molti di questi documenti stanno man mano passando dal processo di digitalizzazione, per evitare il formato cartaceo, soggetto a possibili smarrimenti e furti. <strong>Tra i documenti auto pi\u00f9 importanti c\u2019\u00e8 il Certificato di Propriet\u00e0<\/strong>, che attesta lo stato giuridico del mezzo e che viene rilasciato dalle unit\u00e0 territoriali ACI \u2013 PRA.<\/p>\n<p>A partire dal 2015 il Certificato di Propriet\u00e0 cartaceo \u00e8 stato sostituito dal documento digitale, quindi non \u00e8 pi\u00f9 necessaria la sua presenza in auto per poter circolare su strada. \u00c8 fondamentale per\u00f2 che sia conservato con attenzione, per l\u2019eventuale presentazione al Pubblico Registro Automobilistico.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/info-utili\/cose-il-certificato-di-proprieta-auto-e-a-cosa-serve\/169511\/#Che_cose_il_Foglio_complementare_auto\" title=\"Che cos\u2019\u00e8 il Foglio complementare auto?\">Che cos\u2019\u00e8 il Foglio complementare auto?<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/info-utili\/cose-il-certificato-di-proprieta-auto-e-a-cosa-serve\/169511\/#Certificato_di_Proprieta_digitale_di_che_cosa_si_tratta\" title=\"Certificato di Propriet\u00e0 digitale: di che cosa si tratta\">Certificato di Propriet\u00e0 digitale: di che cosa si tratta<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/info-utili\/cose-il-certificato-di-proprieta-auto-e-a-cosa-serve\/169511\/#Il_Certificato_di_Proprieta_auto_cartaceo\" title=\"Il Certificato di Propriet\u00e0 auto cartaceo\">Il Certificato di Propriet\u00e0 auto cartaceo<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/info-utili\/cose-il-certificato-di-proprieta-auto-e-a-cosa-serve\/169511\/#Che_cosa_succede_se_perdo_il_certificato_di_Proprieta_cartaceo\" title=\"Che cosa succede se perdo il certificato di Propriet\u00e0 cartaceo?\">Che cosa succede se perdo il certificato di Propriet\u00e0 cartaceo?<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Che_cose_il_Foglio_complementare_auto\">Che cos\u2019\u00e8 il Foglio complementare auto?<\/span><\/h2>\n<p>Prima del Certificato di Propriet\u00e0 dell\u2019auto c\u2019era in realt\u00e0 un altro documento, che \u00e8 poi stato sostituito. Parliamo del <strong>Foglio complementare<\/strong>, che non tutti ricorderanno, forse. \u00c8 stato in vigore fino al 1994, ed era proprio il documento che attestava il possesso di un\u2019auto o altro veicolo da parte di un determinato soggetto.<\/p>\n<p>All\u2019interno di questo documento erano infatti segnati tutti i dati del mezzo e anche l\u2019anagrafica del suo proprietario. Il foglio complementare \u00e8 stato sostituito dal suo degno successore, il Certificato di Propriet\u00e0, gi\u00e0 nel 1994. Oggi \u00e8 possibile recuperare il vecchio documento solo in caso di auto storiche o immatricolate prima di quell\u2019anno.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Certificato_di_Proprieta_digitale_di_che_cosa_si_tratta\">Certificato di Propriet\u00e0 digitale: di che cosa si tratta<\/span><\/h2>\n<p>Come ben sappiamo, viviamo nell\u2019era della digitalizzazione e le nuove tecnologie consentono di <strong>dematerializzare<\/strong> anche molti documenti che sono stati cartacei, come quelli relativi al possesso di un\u2019auto o altro veicolo. E infatti anche il Certificato di Propriet\u00e0 \u00e8 diventato digitale a partire dal 2015. Come funziona? Quando si compra un\u2019auto nuova o usata, all\u2019acquirente viene rilasciata <strong>la ricevuta di avvenuta registrazione<\/strong>, che contiene un codice personale, che serve per accedere al portale e visualizzare il proprio documento online.<\/p>\n<p>Il formato digitale \u00e8 stato creato con l\u2019intento di <strong>eliminare il rischio<\/strong> di perdere il documento o di subire un furto dello stesso, o ancora per evitare truffe e contraffazione. Resta chiaramente la possibilit\u00e0 di perdere la ricevuta che contiene il codice personale d\u2019accesso; in questo caso l\u2019automobilista pu\u00f2 richiedere una ristampa gratuita allo Sportello Telematico dell\u2019Automobilista.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Il_Certificato_di_Proprieta_auto_cartaceo\">Il Certificato di Propriet\u00e0 auto cartaceo<\/span><\/h2>\n<p>Tutte le auto che sono state immatricolate tra il 1994 e il mese di ottobre 2015 sono dotate del Certificato di Propriet\u00e0 cartaceo; il formato digitale infatti \u00e8 stato attivato proprio nel 2015. Il documento cartaceo si divide in tre differenti sezioni: nella prima ci sono tutti i dati relativi al <strong>proprietario dell\u2019auto:<\/strong><\/p>\n<ul>\n<li>nome;<\/li>\n<li>cognome;<\/li>\n<li>codice fiscale;<\/li>\n<li>data di nascita;<\/li>\n<li>indirizzo di residenza.<\/li>\n<\/ul>\n<p>Sono presenti anche le <strong>informazioni specifiche sul veicolo:<\/strong><\/p>\n<ul>\n<li>la classe d\u2019uso;<\/li>\n<li>il tipo di auto;<\/li>\n<li>la <a href=\"https:\/\/www.virgilio.it\/motori\/info-utili\/come-capire-lanno-di-immatricolazione-dalla-targa\/168964\/\">data di imma<\/a>t<a href=\"https:\/\/www.virgilio.it\/motori\/info-utili\/come-capire-lanno-di-immatricolazione-dalla-targa\/168964\/\">ricolazione<\/a>;<\/li>\n<li>la potenza;<\/li>\n<li>la tipologia di alimentazione;<\/li>\n<li>eventuali informazioni su fermi amministrativi o gravami fiscali.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Che_cosa_succede_se_perdo_il_certificato_di_Proprieta_cartaceo\">Che cosa succede se perdo il certificato di Propriet\u00e0 cartaceo?<\/span><\/h2>\n<p>Nel caso in cui il Certificato di Propriet\u00e0 cartaceo venga smarrito, allora \u00e8 possibile <strong>fare la richiesta del duplicato<\/strong> all\u2019unit\u00e0 territoriale dell\u2019ACI \u2013 PRA. Nel caso in cui invece l\u2019utente perda la ricevuta relativa al CdP digitale con codice personale per l\u2019accesso al portale, si pu\u00f2 chiedere la ristampa allo Sportello Telematico dell\u2019Automobilista che ha rilasciato la ricevuta in precedenza.<\/p>\n<p>Che <strong>cosa serve<\/strong> per ottenere il duplicato:<\/p>\n<ul>\n<li>denuncia di smarrimento, distruzione o furto del Certificato di Propriet\u00e0 cartaceo alla Polizia o dichiarazione sostitutiva di resa denuncia;<\/li>\n<li>modello NP3C, in doppio originale, compilato e sottoscritto dall\u2019intestatario;<\/li>\n<li>fotocopia di un documento di identit\u00e0 dell\u2019intestatario.<\/li>\n<\/ul>\n<p>Per ottenere il duplicato il costo da sostenere \u00e8 pari a <strong>61,50 euro.<\/strong><\/p>\n<p>Attenzione: se si compra un\u2019auto usata, \u00e8 possibile entrare in possesso del CdP solo dopo l\u2019autentica della firma del venditore sull\u2019atto di vendita e la registrazione del passaggio di propriet\u00e0 presso il PRA.<\/p>\n","protected":false},"excerpt":{"rendered":"Per chi possiede un veicolo uno dei i documenti pi\u00f9 importanti da conservare \u00e8 il Certificato di Propriet\u00e0 dell&#8217;auto: in cosa consiste e qual \u00e8 la sua utilit\u00e0.","protected":false},"author":174233320,"featured_media":169512,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[2040172],"tags":[],"coauthors":[420891121,420891339],"class_list":{"0":"post-169511","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-info-utili","8":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2021\/11\/certificato-di-proprieta-auto.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/169511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/174233320"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=169511"}],"version-history":[{"count":5,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/169511\/revisions"}],"predecessor-version":[{"id":209185,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/169511\/revisions\/209185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/169512"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=169511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=169511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=169511"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=169511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}