{"id":184609,"date":"2022-11-23T12:03:33","date_gmt":"2022-11-23T11:03:33","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=184609"},"modified":"2022-11-23T12:16:23","modified_gmt":"2022-11-23T11:16:23","slug":"hypercar-serie-piu-veloce-mondo-scatto","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/auto\/hypercar-serie-piu-veloce-mondo-scatto\/184609\/","title":{"rendered":"L&#8217;hypercar di serie con lo scatto 0-100 km\/h pi\u00f9 veloce al mondo"},"content":{"rendered":"<p>La Casa automobilistica italiana di lusso Automobili Pininfarina ha confermato le grandi credenziali prestazionali della hypercar Battista GT rivelando per la prima volta <strong>i dati ufficiali di accelerazione e frenata da record<\/strong>. L&#8217;esclusiva tecnologia Launch Control della Battista puramente elettrica contribuisce all&#8217;accelerazione da record delle auto di Formula 1, raggiungendo lo scatto da 0 a 100 in soli 1,86 secondi, 0-120 in 4,49 secondi e 0-200 km\/h in soli 4,79 secondi. <strong>Un gran record.<\/strong><\/p>\n<p>Un&#8217;auto veloce come Battista, avevamo gi&agrave; visto in passato le sue prestazioni, richiede una forte potenza frenante e i test ufficiali confermano che si tratta dell&#8217;EV in frenata pi&ugrave; veloce al mondo, <strong>completando 100-0 km\/h in soli 31 metri<\/strong>. I dati confermati sono stati rivelati mentre la Battista ha fatto il suo debutto dinamico in Medio Oriente, mostrando le sue impareggiabili capacit&agrave; in pista all&#8217;Autodromo di Dubai negli Emirati Arabi.\n<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/hypercar-serie-piu-veloce-mondo-scatto\/184609\/#Il_debutto_della_Battista_di_Pininfarina\" title=\"Il debutto della Battista di Pininfarina\">Il debutto della Battista di Pininfarina<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/hypercar-serie-piu-veloce-mondo-scatto\/184609\/#Il_pacchetto_tecnico_di_Pininfarina_Battista\" title=\"Il pacchetto tecnico di Pininfarina Battista\">Il pacchetto tecnico di Pininfarina Battista<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Il_debutto_della_Battista_di_Pininfarina\">Il debutto della Battista di Pininfarina<\/span><\/h2>\n<p><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/auto-italiana-piu-potente-sempre\/180229\/\">La Pininfarina Battista &egrave; l&rsquo;auto italiana pi&ugrave; potente di sempre, come gi&agrave; sappiamo<\/a>. Il suo debutto dinamico negli Emirati Arabi segue il suo lancio in Arabia Saudita, con partner commerciali locali in ogni Paese. Paolo Dellacha, Chief Product and Engineering Officer di Automobili Pininfarina, ha dichiarato: &ldquo;Sono <strong>orgoglioso<\/strong> che la nostra nuova hyper GT elettrica mantenga le promesse che abbiamo fatto quando abbiamo definito il piano di sviluppo. Con la Battista abbiamo raggiunto prestazioni che vanno oltre i nostri obiettivi originali estremi&rdquo;.<\/p>\n<p>Secondo la Casa, la distribuzione del peso perfettamente ottimizzata e il baricentro basso sono al centro di questo risultato. La combinazione di telaio su misura e messa a punto delle sospensioni, pneumatici collaudati su molte migliaia di miglia di test e quattro motori torque vectoring che forniscono una potenza senza precedenti sono tutte le caratteristiche che permettono alla Battista di essere l<strong>&#8216;auto legale su strada con la pi&ugrave; rapida accelerazione al mondo.<\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Il_pacchetto_tecnico_di_Pininfarina_Battista\">Il pacchetto tecnico di Pininfarina Battista<\/span><\/h2>\n<p>L&#8217;incredibile pacchetto tecnico di Battista include <strong>un sistema frenante in carboceramica<\/strong>, che aiuta l&#8217;hyper GT italiana a diventare l&#8217;auto elettrica con la frenata pi&ugrave; veloce al mondo. I clienti pi&ugrave; esigenti negli Emirati Arabi Uniti sono stati sopraffatti dall&#8217;esperienza di guida della nuova hypercar, che &egrave; mozzafiato quanto il suo premiato design.<\/p>\n<div class=\"iol-media \"><figure id=\"attachment_184612\" aria-describedby=\"caption-attachment-184612\" style=\"width: 1217px\" class=\"wp-caption alignnone iol-media__figure \"><div class=\"iol-media__lnk\"><img loading=\"lazy\" decoding=\"async\" class=\"iol-media__img size-full wp-image-184612\" src=\"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2022\/11\/Pininfarina-Battista_veloce.jpg\" alt=\"L'hypercar di lusso elettrica da record\" width=\"1217\" height=\"694\" srcset=\"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2022\/11\/Pininfarina-Battista_veloce.jpg?resize=1217,694 1217w, https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2022\/11\/Pininfarina-Battista_veloce.jpg?resize=300,171 300w, https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2022\/11\/Pininfarina-Battista_veloce.jpg?resize=687,392 687w, https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2022\/11\/Pininfarina-Battista_veloce.jpg?resize=768,438 768w, https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2022\/11\/Pininfarina-Battista_veloce.jpg?resize=1024,584 1024w, https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2022\/11\/Pininfarina-Battista_veloce.jpg?resize=280,160 280w\" sizes=\"auto, (max-width: 1217px) 100vw, 1217px\" \/><\/div><small class=\"iol-media__copy\"><b class=\"iol-media__copy__src\">Ufficio Stampa Pininfarina<\/b><\/small><figcaption id=\"caption-attachment-184612\" class=\"wp-caption-text iol-media__caption\">L&#8217;hypercar di lusso elettrica da record Pininfarina Battista<\/figcaption><\/figure><\/div>\n<p>La Battista puramente elettrica &egrave; l&#8217;auto italiana pi&ugrave; potente mai realizzata con 1<strong>.900 CV e 2.340 Nm di coppia.<\/strong> L&#8217;hyper GT raggiunge la velocit&agrave; massima di <strong>350 km\/h,<\/strong> vanta un&#8217;autonomia WLTP fino a 476 km e un prezzo a partire da 2,2 milioni di euro pi&ugrave; tasse locali. Le credenziali prestazionali di Battista sono state registrate e verificate a Nard&ograve;, in Italia, come parte del suo programma globale di test e sviluppo all&#8217;inizio di quest&#8217;anno.<\/p>\n<p>Ogni modello di questa fantastica hypercar di lusso elettrica nasce grazie a <strong>oltre 1.250 ore di abile lavoro artigianale<\/strong> a Cambiano, in Italia, dove verranno prodotti non pi&ugrave; di<strong> 150 esemplari.<\/strong> Con un totale di 128 milioni di possibili combinazioni di interni, la nuova hypercar promette nuovi livelli di personalizzazione su misura per tutti i clienti, che potranno quindi scegliere tra livelli quasi illimitati di combinazioni di colori e finiture per gli interni, oltre alle tinte degli esterni con dettagli su misura e design esclusivo dei cerchi in lega.<\/p>\n<p>La Battista &egrave; eccezionale anche per<strong> il suo sound unico, SUONO PURO<\/strong>, che completa l&#8217;esperienza di guida, personalizzabile tramite una delle cinque modalit&agrave; di guida: Pura, Calma, Energica, Furiosa e Carattere. Queste modalit&agrave; distinte conferiscono alla Battista un carattere unico, alterando l&#8217;esperienza a seconda delle preferenze del guidatore.<\/p>\n","protected":false},"excerpt":{"rendered":"Pininfarina Battista \u00e8 la prima hypercar di lusso elettrica al mondo e oggi segna un altro traguardo importante, nuovo record per lo scatto da 0 a 100 km\/h","protected":false},"author":183220656,"featured_media":184611,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420889857],"tags":[420890836,420890809,420890973,420890808,420890893],"coauthors":[420891085],"class_list":{"0":"post-184609","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-auto","8":"tag-auto-elettriche","9":"tag-auto-sportive","10":"tag-freni","11":"tag-hypercar","12":"tag-pininfarina","13":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2022\/11\/Pininfarina-Battista-record.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/184609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220656"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=184609"}],"version-history":[{"count":3,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/184609\/revisions"}],"predecessor-version":[{"id":253998,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/184609\/revisions\/253998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/184611"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=184609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=184609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=184609"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=184609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}