{"id":189290,"date":"2023-03-02T10:45:19","date_gmt":"2023-03-02T09:45:19","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=189290"},"modified":"2024-07-16T10:25:25","modified_gmt":"2024-07-16T08:25:25","slug":"mercato-auto-febbraio-2023-prosegue-la-ripresa","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/auto\/mercato-auto-febbraio-2023-prosegue-la-ripresa\/189290\/","title":{"rendered":"Mercato auto febbraio 2023: prosegue la ripresa"},"content":{"rendered":"<p>Secondo i dati pubblicati dal Ministero delle Infrastrutture e dei Trasporti, a febbraio 2023 il mercato italiano dell&rsquo;auto totalizza <strong>130.365 immatricolazioni<\/strong> (+17,5%) contro le 110.915 unit&agrave; registrate a febbraio 2022.<br \/>\n<img loading=\"lazy\" decoding=\"async\" alt=\"\" class=\"alignnone size-full wp-image-189310\" height=\"2000\" src=\"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2023\/03\/vendita_auto_febbraio23.jpg\" width=\"1217\" srcset=\"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2023\/03\/vendita_auto_febbraio23.jpg?resize=1217,2000 1217w, https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2023\/03\/vendita_auto_febbraio23.jpg?resize=183,300 183w, https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2023\/03\/vendita_auto_febbraio23.jpg?resize=418,687 418w, https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2023\/03\/vendita_auto_febbraio23.jpg?resize=768,1262 768w, https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2023\/03\/vendita_auto_febbraio23.jpg?resize=623,1024 623w, https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2023\/03\/vendita_auto_febbraio23.jpg?resize=935,1536 935w\" sizes=\"auto, (max-width: 1217px) 100vw, 1217px\" \/>\n<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/mercato-auto-febbraio-2023-prosegue-la-ripresa\/189290\/#Il_mercato_auto_di_febbraio_per_alimentazione\" title=\"Il mercato auto di febbraio per alimentazione\">Il mercato auto di febbraio per alimentazione<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/mercato-auto-febbraio-2023-prosegue-la-ripresa\/189290\/#Crescita_a_doppia_cifra_per_DR_Automobiles\" title=\"Crescita a doppia cifra per DR Automobiles\">Crescita a doppia cifra per DR Automobiles<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/mercato-auto-febbraio-2023-prosegue-la-ripresa\/189290\/#Utilitarie_e_SUV_le_auto_preferite\" title=\"Utilitarie e SUV le auto preferite\">Utilitarie e SUV le auto preferite<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/mercato-auto-febbraio-2023-prosegue-la-ripresa\/189290\/#Analisi_dei_canali_di_vendita\" title=\"Analisi dei canali di vendita\">Analisi dei canali di vendita<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Il_mercato_auto_di_febbraio_per_alimentazione\">Il mercato auto di febbraio per alimentazione<\/span><\/h2>\n<p>Analizzando nel dettaglio le immatricolazioni per alimentazione, le <strong>autovetture a benzina<\/strong> vedono il mercato di febbraio aumentare del 16,7%, con quota di mercato al <strong>26,3%,<\/strong> mentre <strong>le diesel <\/strong>crescono dell&rsquo;1,8% rispetto allo stesso mese del 2022, con una quota del <strong>19%<\/strong>. .<\/p>\n<p>Le auto ad alimentazione alternativa rappresentano il 54,7% delle immatricolazioni del solo mese di febbraio, in crescita del 24,2%; nel cumulato aumentano del 21,2% con una quota del 54,5%. Le autovetture elettrificate rappresentano il 44,4% del mercato di febbraio e il 44,2% del cumulato, in aumento del 23,8% nel mese e del 21,5% nel bimestre.<\/p>\n<p>Tra queste, le <strong>ibride<\/strong> non ricaricabili aumentano del 24,3% nel mese e raggiungono una quota del <strong>36,5%<\/strong>; nel cumulato crescono del 23,9%, con una quota del 36,6%. <strong>&nbsp;Le auto elettriche<\/strong> hanno una quota del <strong>3,7% nel mese<\/strong> e del 3,1% nei primi due mesi e aumentano i volumi del 54% a febbraio e del 19,1% nel cumulato.<\/p>\n<p>Infine, le autovetture a gas rappresentano il 10,2% dell&rsquo;immatricolato di febbraio, di cui il 10% &egrave; rappresentato da autovetture Gpl (+42%) e lo 0,2% da autovetture a metano (-81,8%), mentre nel cumulato rappresentano il 10,3% del mercato, con il metano che cala dell&rsquo;80,7% e il GPL che cresce del 35,1%.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Crescita_a_doppia_cifra_per_DR_Automobiles\">Crescita a doppia cifra per DR Automobiles<\/span><\/h2>\n<p>Nel mese, <a href=\"https:\/\/www.virgilio.it\/motori\/listino\/fiat\/fiat-panda\/\">Fiat Panda<\/a>, <a href=\"https:\/\/www.virgilio.it\/motori\/listino\/fiat\/fiat-500\/\">Fiat 500<\/a> e<a href=\"https:\/\/www.virgilio.it\/motori\/listino\/lancia\/lancia-ypsilon\/\"> Lancia Ypsilon<\/a> &nbsp;ibride occupano rispettivamente la prima, la terza e la quarta posizione tra le autovetture mild\/full hybrid. Tra le PHEV, attualmente<a href=\"https:\/\/www.virgilio.it\/motori\/listino\/jeep\/jeep-compass\/\"> Jeep Compass<\/a> &egrave; il modello pi&ugrave; venduto e <a href=\"https:\/\/www.virgilio.it\/motori\/listino\/jeep\/jeep-renegade\/\">Jeep Renegade<\/a> &egrave; al terzo posto. Entra nella top ten delle plug-in di febbraio anche <a href=\"https:\/\/www.virgilio.it\/motori\/listino\/alfa-romeo\/alfa-romeo-tonale\/\">Alfa Romeo Tonale<\/a>, al settimo posto. Tra le elettriche, Fiat 500 risulta, nel mese, il secondo modello pi&ugrave; venduto, mentre <a href=\"https:\/\/www.virgilio.it\/motori\/listino\/peugeot\/peugeot-208\/\">Peugeot 208<\/a> occupa la settima posizione.<\/p>\n<p>Ancora <a href=\"https:\/\/www.virgilio.it\/motori\/listino\/dr\/\">in crescita a doppia cifra il mercato di DR Automobiles<\/a>, sia a febbraio (+94,1%) che nel cumulato (+53,4%). Rispetto a febbraio 2022, <strong>il costruttore molisano<\/strong> guadagna 1 punto percentuale di quota nel secondo mese del 2023 e sale a 2,4%, mentre nel bimestre detiene una quota di mercato dell&rsquo;1,8% (era 1,4% nel primo bimestre 2022). Tra i marchi di origine cinese da segnalare <strong>Lynk &amp; Co<\/strong> (422 auto, +191%) e&nbsp; <strong>MG<\/strong> (1.028 auto, +137,4%).<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Utilitarie_e_SUV_le_auto_preferite\">Utilitarie e SUV le auto preferite<\/span><\/h2>\n<p>In riferimento al mercato per segmenti, nel mese di febbraio le <strong>autovetture utilitarie rappresentano il 31,1% del mercato<\/strong>, in aumento dell&rsquo;1,8%. Il modello pi&ugrave; venduto rimane Fiat Panda, seguito da Fiat 500.<\/p>\n<p><strong>I SUV hanno una quota di mercato pari al 55,4%,<\/strong> in aumento del 27,6%. Nel dettaglio, i SUV piccoli rappresentano il 25% del mercato del mese (+13,4% rispetto a febbraio 2022), i SUV compatti il 22,9% (+36,9%) e i SUV medi il 6,3%, (+69%), mentre le vendite di SUV grandi sono l&rsquo;1,2% del totale (+27%). Il 24,8% dei SUV venduti &egrave; di un brand del Gruppo Stellantis.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Analisi_dei_canali_di_vendita\">Analisi dei canali di vendita<\/span><\/h2>\n<p>Per quanto riguarda i canali di vendita &egrave; il noleggio a sostenere la domanda, a dimostrazione dell&rsquo;efficacia dell&rsquo;ampliamento della platea dei beneficiari degli incentivi proprio alle persone giuridiche. I privati, infatti, crescono del 2,9%, ma il noleggio a lungo termine vola a +54,8% e quello a breve a +147,7%. Bene anche le societ&agrave;, con un +32,7%. Le auto immatricolazioni, invece, scendono del 6,4%.<\/p>\n<p><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/mercato-auto-in-europa-a-gennaio-2023\/189057\/\">MERCATO AUTO: I NUMERI DI GENNAIO 2023<\/a><br \/>\n<a data-doctype=\"\" href=\"https:\/\/www.virgilio.it\/motori\/auto\/mercato-auto-dicembre-2022-lanno-si-chiude-con-un-segno-positivo\/187031\/\"><strong>MERCATO AUTO: I NUMERI DI DICEMBRE 2022<\/strong><\/a><br \/>\nMERCATO AUTO: I NUMERI DI NOVEMBRE 2022<br \/>\n<a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/mercato-auto-in-italia-i-numeri-delle-immatricolazioni-di-ottobre-2022\/183881\/\"><strong>MERCATO AUTO: I NUMERI DI OTTOBRE 2022<\/strong><\/a><br \/>\n<a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/auto-piu-vendute-settembre-2022-italia\/182266\/\"><strong>MERCATO AUTO: I NUMERI DI SETTEMBRE 2022<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Secondo i dati pubblicati dal Ministero delle Infrastrutture e dei Trasporti, a febbraio 2023 il mercato italiano dell&rsquo;auto totalizza 130.365 immatricolazioni (+17,5%) contro ","protected":false},"author":91371793,"featured_media":189322,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420889857],"tags":[420890838],"coauthors":[393837918,420891334],"class_list":{"0":"post-189290","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-auto","8":"tag-immatricolazione-auto","9":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2023\/03\/infografica.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/189290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/91371793"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=189290"}],"version-history":[{"count":30,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/189290\/revisions"}],"predecessor-version":[{"id":265260,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/189290\/revisions\/265260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/189322"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=189290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=189290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=189290"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=189290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}