{"id":205570,"date":"2023-10-10T10:39:13","date_gmt":"2023-10-10T08:39:13","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=205570"},"modified":"2023-10-10T10:39:13","modified_gmt":"2023-10-10T08:39:13","slug":"f1-offerta-record-diritti-tv-apple","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/motor-sport\/f1-offerta-record-diritti-tv-apple\/205570\/","title":{"rendered":"F1, offerta record per i diritti TV: spunta Apple"},"content":{"rendered":"<p>Dall&#8217;estero arrivano sempre pi\u00f9 notizie che annunciano l&#8217;arrivo di Apple in F1. Nello specifico, in ballo ci sono i<strong> diritti TV per la trasmissione globale dei GP di Formula 1<\/strong> dopo il 2025. Una volont\u00e0 da esercitare per almeno 5 stagioni mondiali a seguire.<\/p>\n<p>La trattativa con Formula One Group partirebbe dall&#8217;importante cifra di <strong>2 miliardi di dollari all&#8217;anno<\/strong>. Un&#8217;offerta di rilievo, circa il doppio di quella che attualmente viene percepita vendendo i diritti in 20 paesi e cinque continenti.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/f1-offerta-record-diritti-tv-apple\/205570\/#Idea_Apple\" title=\"Idea Apple\">Idea Apple<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/f1-offerta-record-diritti-tv-apple\/205570\/#Formula_One_Group\" title=\"Formula One Group\">Formula One Group<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/f1-offerta-record-diritti-tv-apple\/205570\/#Film_Apple\" title=\"Film Apple\">Film Apple<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/f1-offerta-record-diritti-tv-apple\/205570\/#Rivoluzione_sport_dal_vivo\" title=\"Rivoluzione sport dal vivo\">Rivoluzione sport dal vivo<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Idea_Apple\">Idea Apple<\/span><\/h2>\n<p>Per media esteri, Apple fa sul serio in F1. Sempre pi\u00f9 rumors la segnalano come prossimo broadcaster ufficiale della F1. Pronta un&#8217;offerta da capogiro per conquistare i paesi dove non esistono esclusive. A seguire si prevedono offerte mirate per conquistare tutto il mercato globale e <strong>riunire le trasmissioni sotto un&#8217;unica emittente<\/strong>. Alla base del progetto anche la possibilit\u00e0 di trasportare i GP in streaming su mobile e applicazioni dedicate. Una rivoluzione che strizza l&#8217;occhio ai pi\u00f9 giovani e alle nuove tecnologie.<\/p>\n<p>La Formula 1 si trova davanti a un bivio decisionale, continuare a frammentare i diritti attraverso pi\u00f9 broadcaster o centralizzare il tutto sotto un unico &#8220;faro&#8221;. Attualmente la competizione \u00e8 trasmessa dalla RTL in Germania, dalla British Broadcasting Corporation (BBC) in Inghilterra, da The Sports Network in Canada, Network Ten e One in Australia e Al Jazeera nel Medio Oriente. Dal 2018 Sky ha ottenuto l&#8217;esclusiva dei Gran Premi in Italia, con l&#8217;uscita di scena della Rai. Le gare vengono attualmente trasmesse su Sky Sport, Now Tv e Tv 8. Un&#8217;esclusiva che terminer\u00e0 soltanto nel 2027.<\/p>\n<p>Intanto la battaglia per i diritti negli USA si prepara ad assumere i contorni di una sfida tra titani. <strong>Apple infatti prover\u00e0 in tutti i modi a sottrarre i diritti all&#8217;emittente ESPN (Disney)<\/strong> che attualmente trasmette in diretta esclusiva i weekend di gara in Formula 1. Tali diritti scadranno nel 2025 e a breve si apriranno le trattative per rinnovi o nuove collaborazioni. Attualmente \u00e8 in corso un contratto che fornisce 90 milioni di dollari all&#8217;anno alle casse della Formula One Group, agenzia che cura i diritti per la F1. Da tenere d&#8217;occhio anche Amazon, Comcast e Netflix, sempre pronte a partecipare alla bagarre nonostante i precedenti del 2022.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Formula_One_Group\">Formula One Group<\/span><\/h2>\n<p>Formula One Group \u00e8 un&#8217;entit\u00e0 privata in stretta relazione coi media e le questioni organizzative riguardanti la Formula 1, tramite varie sussidiarie tra cui la Formula One Management e la Formula One Promotions and Administration. Il presidente e amministratore delegato del Formula One Group \u00e8 attualmente <strong>Stefano Domenicali<\/strong> che \u00e8 succeduto a Chase Carey dal gennaio 2021.<\/p>\n<p>La FOM \u00e8 quotata in borsa e mantiene i diritti commerciali sui nomi delle scuderie, il logo ufficiale della Formula 1 e tutti i contenuti dei media che riguardano la massima serie automobilistica. Le ultime indiscrezioni non confermate e non commentate ufficialmente dai vertici del gruppo, hanno gi\u00e0 prodotto delle fluttuazioni positive di borsa e subbuglio in rete.<\/p>\n<p><strong>Formula One Group \u00e8 protagonista indiscusso<\/strong> del nuovo successo mediatico della F1. Da una media di 400 milioni di spettatori \u00e8 passata nelle ultime stagioni a una <strong>media di 1 miliardo<\/strong>. Gare pi\u00f9 equilibrate (nonostante il predominio assoluto di Red Bull e <a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/f1-record-verstappen-meglio-anche-vettel\/197423\/\" target=\"_blank\" rel=\"noopener\" data-doctype=\"\">Max Verstappen<\/a>) e nuovi regolamenti hanno conquistato nuove nicchie di spettatori e nuove nazioni. Lo stesso Domenicali qualche mese fa aveva accennato la volont\u00e0 di portare la Formula 1 ad avere gare pi\u00f9 aperte e imprevedibili. Nel mirino la possibile riduzione di prove libere, nuovi circuiti, nuovi team e il sogno di un GP in Africa. Tutte considerazioni che piano piano sembrerebbero concretizzarsi.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Film_Apple\">Film Apple<\/span><\/h2>\n<p>L&#8217;interesse di Apple per il circus della F1 \u00e8 testimoniato anche dal documentario appena realizzato su Hamilton e dalla produzione cinematografica attualmente in via di sviluppo. Un film con la regia di <strong>Joseph Kosinski<\/strong>, lo stesso di Top Gun: Maverick. Una pellicola d&#8217;azione attualmente ancora senza titolo ma dal copione gi\u00e0 scritto da Ehren Kruger e prodotto da Jerry Bruckheimer.<\/p>\n<p>Protagonista principale <strong>Brad Pitt<\/strong> che interpreta un ex-pilota di F1 tornato a correre. Nel cast anche Damson Idris, Kerry Condon, Tobias Menzies, il pluricampione Lewis Hamilton e Javier Bardem. Prodotto in collaborazione con la F1, \u00e8 stato e viene girato durante i weekend di gara del mondiale; le ultime riprese sono previste ad Abu Dhabi a novembre.<\/p>\n<p>Sempre secondo indiscrezioni in rete, il film di Apple, avr\u00e0 una distribuzione esclusiva a livello globale. Dopo un periodo di distribuzione sar\u00e0 sicuramente disponibile per la piattaforma AppleTV+. Le prime immagini a produzione conclusa si potranno ammirare solo nel 2024.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Rivoluzione_sport_dal_vivo\">Rivoluzione sport dal vivo<\/span><\/h2>\n<p><strong>Gli sport dal vivo sono l&#8217;ultima frontiera delle pay TV<\/strong>. La situazione generale sta evolvendo con le ultime intenzioni strategiche di Apple e Amazon. La Formula 1 ad esempio \u00e8 solo una piccola parte del sistema, ma \u00e8 una nicchia molto apprezzata, anche pi\u00f9 del calcio e del tennis.<\/p>\n<p>La crescita dei dispositivi mobile ha amplificato la competizione e reso la platea di fruitori molto pi\u00f9 ampia. A ci\u00f2 per\u00f2 c&#8217;\u00e8 anche un limite importante da risolvere,\u00a0 la vera e propria scommessa tecnologica dei prossimi anni. Per trasmettere tramite app un evento ad un gran numero di milioni di persone, si rende necessaria una sofisticata infrastruttura, enorme e funzionante. \u00c8 giunto il tempo di testare l&#8217;emissione di spettacolo ed energia.<\/p>\n","protected":false},"excerpt":{"rendered":"Apple interessata ad acquisire i diritti TV globali della F1. Sul piatto un&#8217;offerta da capogiro intorno i 2 milioni di dollari all&#8217;anno per 5 anni","protected":false},"author":183220820,"featured_media":205573,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420891318],"tags":[],"coauthors":[420891321,420891319],"class_list":{"0":"post-205570","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-motor-sport","8":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2023\/10\/apple-diritti-tv-f1.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/205570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220820"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=205570"}],"version-history":[{"count":6,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/205570\/revisions"}],"predecessor-version":[{"id":205585,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/205570\/revisions\/205585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/205573"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=205570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=205570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=205570"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=205570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}