{"id":206231,"date":"2023-10-22T12:46:29","date_gmt":"2023-10-22T10:46:29","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=206231"},"modified":"2025-02-07T15:40:52","modified_gmt":"2025-02-07T14:40:52","slug":"honda-svela-nuovo-sh-vetro-scooter-semi-trasparente","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/moto\/honda-svela-nuovo-sh-vetro-scooter-semi-trasparente\/206231\/","title":{"rendered":"Honda svela il nuovo SH Vetro, lo scooter &#8220;semi-trasparente&#8221;"},"content":{"rendered":"<p>Honda presenta gli aggiornamenti della sua gamma di scooter pi\u00f9 prestigiosa ed efficiente, la famiglia SH, a partire dal nuovo modello <strong>SH Vetro<\/strong>, caratterizzato da una carrozzeria semi-trasparente verde realizzata con uno speciale materiale.<\/p>\n<p>Il nuovo SH Vetro di Honda \u00e8 frutto di tutto l&#8217;ingegno e di tutte le capacit\u00e0 tecniche di chi ogni giorno lavora con passione presso la fabbrica italiana del brand nipponico situata ad <strong>Atessa<\/strong>, in provincia di Chieti, stabilimento che ancora una volta \u00e8 il fiore all&#8217;occhiello della produzione della Casa dell&#8217;Ala.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/moto\/honda-svela-nuovo-sh-vetro-scooter-semi-trasparente\/206231\/#Honda_SH_Vetro_lo_scooter_diventa_semi-trasparente\" title=\"Honda SH Vetro: lo scooter diventa &#8220;semi-trasparente&#8221;\">Honda SH Vetro: lo scooter diventa &#8220;semi-trasparente&#8221;<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/moto\/honda-svela-nuovo-sh-vetro-scooter-semi-trasparente\/206231\/#Colori_e_configurazioni\" title=\"Colori e configurazioni\">Colori e configurazioni<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Honda_SH_Vetro_lo_scooter_diventa_semi-trasparente\">Honda SH Vetro: lo scooter diventa &#8220;semi-trasparente&#8221;<\/span><\/h2>\n<p>La novit\u00e0 che pi\u00f9 di tutte salta all&#8217;occhio \u00e8 <strong>la carrozzeria semi-trasparente<\/strong> verde del nuovo Honda SH Vetro, realizzata in uno speciale materiale che nel corso del processo di produzione consente di abbattere le emissioni di CO2 del 9,5% su base annua rispetto alle colorazioni classiche.<\/p>\n<p>La carrozzeria semi-trasparente di colore verde \u00e8 a tutti gli effetti una nuova livrea lanciata sui modelli della famiglia di SH da parte di Honda, brand che nei mesi scorsi ha <a href=\"https:\/\/www.virgilio.it\/motori\/moto\/honda-svela-ultima-naked-superleggera\/172389\/\">svelato la sua ultima naked superleggera<\/a>. La nuova livrea \u00e8 accompagnata dal parafango anteriore e dalle carene inferiori di colore nero, a contrasto con il logo Honda bianco e il logo SH in argento poste sulle fiancate dello scooter.<\/p>\n<p>L&#8217;SH Vetro di Honda, societ\u00e0 che ha da poco stretto uno storico accordo con Sony per le auto elettriche, viene declinato nelle versioni SH125i, SH150i che insieme a SH Mode 125 sono i primi modelli della Casa giapponese capaci di soddisfare i requisiti sulle emissioni della normativa Euro 5+, obbligatoria dal 2024 per tutte le nuove omologazioni e dal 2025 per quanto riguarda le nuove immatricolazioni.<\/p>\n<p>Con la <strong>normativa Euro 5+<\/strong> \u00e8 stato introdotto il monitoraggio del catalizzatore per ridurre il margine di letture errate delle emissioni, garantire un maggiore controllo della rumorosit\u00e0 e delle emissioni acustiche allo scarico e verificare il reale deterioramento a lungo termine.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Colori_e_configurazioni\">Colori e configurazioni<\/span><\/h2>\n<p>Il modello <strong>Honda SH125 150i<\/strong> \u00e8 in vendita in Italia nella configurazione con parabrezza, paramani e Smart-Top Box di serie nelle seguenti colorazioni: Vetro Green (SH Vetro), Mat Pearl Cool White (Sporty), Mat Coal Black Metallic (Sporty),\u00a0 Pearl Pacific Blue, Mat Pearl Cool White, Pearl Falcon Gray e Pearl Nightstar Black.<\/p>\n<p>L&#8217;<strong>SH350i<\/strong>, invece, \u00e8 disponibile nei seguenti colori, tutti caratterizzati da ruote, forcella e marmitta in nero: Black, Mat Ruthenium Silver Metallic, Mat Pearl Cool White, Zefiro Blue Metallic, Mat Techno Silver Metallic (Sporty) e Mat Coal Black Metallic (Sporty).<\/p>\n<p>Tutti i modelli 2024 della famiglia SH saranno disponibili presso le concessionarie ufficiali Honda a partire dal mese di dicembre del 2023: con oltre 45.000 unit\u00e0 vendute in Europa sin dalla sua introduzione sul mercato nel 2014, l&#8217;SH Mode 125 \u00e8 riuscito a calamitare l&#8217;interesse degli utenti pi\u00f9 giovani, grazie a una perfetta combinazione di elementi di stile, performance gestibili e ridottissimi costi di gestione.<\/p>\n<p>I numeri di SH, in oltre trent&#8217;anni di presenza sul mercato, continuano a essere straordinari, non solo a livello internazionale ma anche in Italia: basti pensare che nel nostro Paese sono gi\u00e0 pi\u00f9 di 33 mila gli SH di tutte le cilindrate venduti dall&#8217;inizio del 2023. Numeri destinati a crescere negli ultimi due mesi dell&#8217;anno, proiettando il brand nipponico verso un 2024 che si annuncia roseo con l&#8217;avvento della <strong>nuova gamma<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"Honda presenta il nuovo scooter SH Vetro, modello caratterizzato da una carrozzeria semi-trasparente verde realizzata nello stabilimento di Atessa","protected":false},"author":158396758,"featured_media":206232,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420889858],"tags":[420890846,420890850],"coauthors":[420890778,420891339],"class_list":{"0":"post-206231","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-moto","8":"tag-honda","9":"tag-scooter","10":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2023\/10\/Honda-SH-Vetro.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/206231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/158396758"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=206231"}],"version-history":[{"count":4,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/206231\/revisions"}],"predecessor-version":[{"id":267459,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/206231\/revisions\/267459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/206232"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=206231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=206231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=206231"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=206231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}