{"id":209947,"date":"2023-12-30T10:25:01","date_gmt":"2023-12-30T09:25:01","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=209947"},"modified":"2024-07-16T11:05:30","modified_gmt":"2024-07-16T09:05:30","slug":"ritrovate-32-auto-due-moto-rubate-italia","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/notizie\/ritrovate-32-auto-due-moto-rubate-italia\/209947\/","title":{"rendered":"Ritrovate 32 auto e due moto rubate in Italia"},"content":{"rendered":"<p>I <strong>furti d\u2019auto<\/strong> sono tutt\u2019altro che un fenomeno superato o fuori moda. Al contrario, gli scassinatori di oggi hanno sviluppato <strong>nuovi metodi<\/strong> per sottrarre le auto ai legittimi proprietari, e in alcuni casi puntano ad alcuni componenti specifici della vettura, come catalizzatori e volanti tech.<\/p>\n<p>Soltanto negli ultimi giorni &#8211; tra Sicilia, Puglia e Campania &#8211; sono state rinvenute <strong>oltre 50 auto rubate (e 2 moto)<\/strong>: 32 a Catania, 16 a Brindisi e 8 in un capannone di Arzano, in provincia di Napoli. Tutte le vetture sono state <strong>restituite<\/strong> ai proprietari, cittadini e turisti che si erano visti sottrarre l\u2019auto nei mesi scorsi.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/ritrovate-32-auto-due-moto-rubate-italia\/209947\/#Catania_restituite_32_auto_e_2_moto_rubate\" title=\"Catania, restituite 32 auto e 2 moto rubate\">Catania, restituite 32 auto e 2 moto rubate<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/ritrovate-32-auto-due-moto-rubate-italia\/209947\/#Furti_dauto_in_Italia_non_abbassare_la_guardia\" title=\"Furti d\u2019auto in Italia: non abbassare la guardia\">Furti d\u2019auto in Italia: non abbassare la guardia<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Catania_restituite_32_auto_e_2_moto_rubate\">Catania, restituite 32 auto e 2 moto rubate<\/span><\/h2>\n<p>Le operazioni di controllo della Guardia di Finanza di <strong>Catania<\/strong>, intensificate negli ultimi tre mesi soprattutto nei quartieri di Nesima, San Cristoforo e Librino, hanno portato alla scoperta di<strong> decine auto rubate<\/strong>, di propriet\u00e0 di cittadini catanesi ma anche di turisti che avevano scelto di passare le vacanze in Sicilia.<\/p>\n<p>Le auto rubate sono risultate perlopi\u00f9 di recente immatricolazione: un dato curioso, se consideriamo le statistiche sui furti d\u2019auto in Italia. I modelli rinvenuti, invece, non stupiscono pi\u00f9 di tanto: anche se adesso i malfattori prediligono esemplari pi\u00f9 recenti, i modelli \u201cdi punta\u201d sembrano restare quelli di sempre. <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/fiat\/fiat-panda\/\">Fiat Panda<\/a><\/strong>, <a href=\"https:\/\/www.virgilio.it\/motori\/auto\/video\/auto-piu-rubate-italia-nuova-classifica\/194548\/\">da sempre la pi\u00f9 amata dai ladri<\/a>, e numerose <strong>Lancia Y<\/strong>. Ma anche vecchie glorie come Fiat Scudo e Grande Punto. Tutti i veicoli rinvenuti dalla GdF &#8211; <strong>32 automobili e 2 motoveicoli<\/strong> &#8211; sono stati restituiti ai legittimi proprietari.<\/p>\n<p>Se al nord i furti riguardano soprattutto SUV e singole componenti di auto di grossa cilindrata, al sud <a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/furti-auto-in-crescita-allerta-rossa-per-questi-modelli\/189176\/\">le auto pi\u00f9 rubate restano le utilitarie<\/a>. Diverse anche le <strong>modalit\u00e0 di furto<\/strong>, tra un capo e l\u2019altro del Paese: mentre auto e componenti sottratti al nord vengono subito rivenduti o spediti all\u2019estero, lasciando ben poche speranze ai proprietari, i furti d\u2019auto nelle regioni del sud sono ancora legati al cosiddetto \u201ccavallo di ritorno\u201d, quindi \u00e8 pi\u00f9 probabile che le auto sottratte restino integre e nei paraggi.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Furti_dauto_in_Italia_non_abbassare_la_guardia\">Furti d\u2019auto in Italia: non abbassare la guardia<\/span><\/h2>\n<p>Negli ultimi giorni si sono intensificati anche i controlli del Comando Provinciale dei Carabinieri di <strong>Brindisi<\/strong>, che hanno rinvenuto e restituito ai proprietari ben 16 automobili rubate. E nella provincia di Napoli, ad <strong>Arzano<\/strong>, le Forze dell\u2019Ordine hanno scoperto un parcheggio in cui c\u2019erano solo auto rubate, 8 veicoli per la precisione.<\/p>\n<p>Negli stessi giorni, la Polizia di Stato del commissariato di <strong>Acireale<\/strong> ha scoperto in un edificio abbandonato un vero e proprio deposito di veicoli rubati: sono stati rinvenuti parti di carrozzeria, tappezzeria, componenti meccanici ed elettronici, una moto senza targa e con il telaio cancellato e un\u2019auto &#8211; rubata pochi giorni fa &#8211; che era stata \u201cmascherata\u201d da un cambio targa truffaldino e che \u00e8 stata riconosciuta soltanto grazie al numero di telaio.<\/p>\n<p>Se \u00e8 vero che questi numeri &#8211; che fanno riferimento a <strong>poche settimane di controlli<\/strong> &#8211; possono non stupire, \u00e8 altrettanto vero che danno la misura di un fenomeno che non accenna a diminuire nel nostro Paese. Al contrario, i ladri d\u2019auto stanno sviluppando metodi sempre pi\u00f9 veloci ed efficienti per rubare le vetture parcheggiate in strada: dalla clonazione delle chiavi al furto con &#8220;<strong>Relay Attack<\/strong>&#8220;, che in pochi istanti pu\u00f2 neutralizzare la sicurezza di qualunque auto con apertura keyless.<\/p>\n<p>Le strategie per tentare di sottrarsi alla spirale di furti e ruberie che si va consumando per le strade italiane sono sempre le stesse: evitare <strong>parcheggi isolati o poco illuminati<\/strong>, controllare sempre manualmente di aver chiuso le portiere dell\u2019auto e dotarsi di <a href=\"https:\/\/www.virgilio.it\/motori\/info-utili\/furti-auto-nuova-tecnologia-recuperare-veicoli-rubati\/205558\/\">alcuni strumenti utili (e poco costosi)<\/a> che permettono di proteggere la propria auto tramite localizzazione GPS, stacco batteria o blocco dello sterzo.<\/p>\n","protected":false},"excerpt":{"rendered":"Nel giro di pochi giorni le Forze dell&#8217;Ordine di Campania, Puglia e Sicilia hanno rinvenuto (e restituito ai proprietari) oltre 50 auto rubate","protected":false},"author":183220806,"featured_media":209948,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[25915],"tags":[],"coauthors":[420891313,420891292],"class_list":{"0":"post-209947","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-notizie","8":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2023\/12\/furti-auto-italia.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/209947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220806"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=209947"}],"version-history":[{"count":2,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/209947\/revisions"}],"predecessor-version":[{"id":236962,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/209947\/revisions\/236962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/209948"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=209947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=209947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=209947"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=209947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}