{"id":210167,"date":"2024-01-05T17:10:39","date_gmt":"2024-01-05T16:10:39","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=210167"},"modified":"2024-06-25T08:16:21","modified_gmt":"2024-06-25T06:16:21","slug":"rara-ferrari-sogno-leclerc-pezzo-unico-costosissimo","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/curiosita\/rara-ferrari-sogno-leclerc-pezzo-unico-costosissimo\/210167\/","title":{"rendered":"La rara Ferrari da sogno di Leclerc: pezzo unico e costosissimo"},"content":{"rendered":"<p>Uno dei modelli pi&ugrave; costosi ed esclusivi al mondo del Cavallino Rampante,<strong> una Ferrari 812 Competizione Aperta<\/strong>: &egrave; questo il meraviglioso gioiellino che Charles Lecler si &egrave; appena regalato, per inaugurare il 2024 in grande stile. Il pilota della Ferrari di Formula 1 ha comprato una bellissima e rara supercar di Maranello e ha deciso anche di fare aggiungere alcune personalizzazioni ad hoc, che la rendono unica al mondo.\n<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/curiosita\/rara-ferrari-sogno-leclerc-pezzo-unico-costosissimo\/210167\/#Le_vacanze_di_Leclerc_allinsegna_del_Cavallino_Rampante\" title=\"Le vacanze di Leclerc, all&rsquo;insegna del Cavallino Rampante\">Le vacanze di Leclerc, all&rsquo;insegna del Cavallino Rampante<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/curiosita\/rara-ferrari-sogno-leclerc-pezzo-unico-costosissimo\/210167\/#La_supercar_di_Leclerc\" title=\"La supercar di Leclerc\">La supercar di Leclerc<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Le_vacanze_di_Leclerc_allinsegna_del_Cavallino_Rampante\">Le vacanze di Leclerc, all&rsquo;insegna del Cavallino Rampante<\/span><\/h2>\n<p>Terminato il campionato 2023 di Formula 1 che abbiamo seguito nel dettaglio, <strong>i piloti si prendono una pausa dalle corse<\/strong>, in corrispondenza delle vacanze di Natale. Riposo, momenti in famiglia e gite con gli amici: &egrave; quello che serve per rilassarsi dopo un&rsquo;impegnativa stagione intera.<\/p>\n<p>Ma Charles Leclerc, <a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/ferrari-f1-pronto-rinnovo-leclerc-cifre-record\/208708\/\">pilota di Formula 1 della squadra Ferrari (in trattativa per un nuovo accordo)<\/a>, sembra non abbandonare il pensiero del Cavallino Rampante anche durante le sue ferie.<strong> La grande passione per il marchio italiano<\/strong> si fa notare anche fuori dalle piste, nella vita privata.<\/p>\n<p>Il monegasco infatti ha deciso di farsi<strong> un super auto-regalo per inaugurare il 2024<\/strong> appena iniziato: nel suo garage entra una nuova supercar, un modello molto raro e prezioso, che solo personaggi come lui possono permettersi. Stiamo parlando proprio di una vettura del Cavallino Rampante, appunto,<strong> una Ferrari 812 Competizione Aperta.<\/strong> Modello gi&agrave; di per s&eacute; raro, ma che il pilota ha deciso di farsi personalizzare, rendendolo praticamente unico al mondo.<\/p>\n<p>Il 26enne ha passato le sue vacanze e festeggiato l&rsquo;ultimo dell&rsquo;anno nella sua Monte Carlo, regalandosi questo meraviglioso modello uscito dalla Casa di Maranello, con cui ha gi&agrave; iniziato a sfrecciare per le vie pi&ugrave; esclusive del Principato. Di sicuro non passa inosservato, anzi, attira gli sguardi di tutti i passanti.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"La_supercar_di_Leclerc\">La supercar di Leclerc<\/span><\/h2>\n<p>L&rsquo;auto estrema che &egrave; finita nel garage di Charles Cleclerc fa parte delle sole<strong> 599 unit&agrave; che esistono al mondo<\/strong> della bellissima Ferrari 812 Competizione Aperta. Un modello gi&agrave; sold out, ancora prima di uscire dalle linee di produzione, come spesso accade per questi bolidi rari e preziosi.<\/p>\n\n\t\t<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/C1tiLFfqRCx\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:100%; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/C1tiLFfqRCx\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Visualizza questo post su Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><\/div><\/blockquote>\n\t\t\n<p><strong>Il prezzo di listino? Parte da 578.000 euro<\/strong>, ma non dimentichiamo che il pilota monegasco l&rsquo;ha fatta modificare con personalizzazioni ad hoc. Il modello in particolare riprende le linee della mitica 812 Superfast con tetto apribile, derivata dalla 812 GTS. Il motore &egrave; ancora pi&ugrave; potente di quello gi&agrave; estremo della sua antenata, in questo caso si tratta della massima evoluzione del V12 6.5 aspirato, in grado di erogare la potenza di <strong>830 CV<\/strong> e di viaggiare anche superando i <strong>340 km\/h<\/strong> di velocit&agrave; massima, scattando da 0 a 100 km\/h in soli 2,85 secondi.<\/p>\n<p>Charles Leclerc aggiunge quindi alla sua collezione privata un nuovissimo gioiellino prezioso. Nel suo garage, come potete immaginare, ci sono gi&agrave; dei pezzi magnifici, come la Ferrari 488 Pista e la Lamborghini Huracan STO.<\/p>\n<p>E per quanto riguarda la personalizzazione alla sua 812 Competizione Aperta? Il monegasco ha fatto aggiungere un particolare che rende la supercar differente da tutti gli altri 598 esemplari al mondo. Parliamo del <strong>numero 16 inserito nella parte anteriore dell&rsquo;auto<\/strong>, che come sappiamo &egrave; il numero di gara con cui corre con Ferrari nel Mondiale di Formula 1.<\/p>\n","protected":false},"excerpt":{"rendered":"Charles Leclerc, noto pilota di F1, ha comprato una nuova, rarissima e costosissima Ferrari da urlo: una 812 Competizione Aperta personalizzata","protected":false},"author":183220656,"featured_media":210203,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420890037],"tags":[420890809,420891255,420890863,420890808,420890940],"coauthors":[420891085,420891167],"class_list":{"0":"post-210167","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-curiosita","8":"tag-auto-sportive","9":"tag-charles-leclerc","10":"tag-ferrari","11":"tag-hypercar","12":"tag-maranello","13":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2024\/01\/Ferrari-812-competizione-aperta-Leclerc.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/210167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220656"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=210167"}],"version-history":[{"count":6,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/210167\/revisions"}],"predecessor-version":[{"id":265627,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/210167\/revisions\/265627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/210203"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=210167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=210167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=210167"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=210167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}