{"id":213165,"date":"2024-02-19T11:44:50","date_gmt":"2024-02-19T10:44:50","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=213165"},"modified":"2024-02-19T11:44:50","modified_gmt":"2024-02-19T10:44:50","slug":"ferrari-gioielli-piu-rari-costosi-sempre","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/auto\/ferrari-gioielli-piu-rari-costosi-sempre\/213165\/","title":{"rendered":"Ferrari, uno dei gioielli pi\u00f9 rari (e costosi) di sempre"},"content":{"rendered":"<p>Sta per andare <strong>all&rsquo;asta per RM Sotheby&rsquo;s<\/strong> a Detroit un rarissimo esemplare di <strong>Testa Rossa con parafango a pontone<\/strong>. La vettura, uno dei 19 esemplari speciali realizzati dal celebre carrozziere italiano Sergio Scaglietti, &egrave; stata completamente restaurata da Ferrari Classiche nel 2013 ed &egrave; tra i pochissimi esemplari a poter vantare il <strong>Libretto Rosso<\/strong> &#8211; conservando motore e cambio originali con numeri di matricola.<\/p>\n<p>La Ferrari 250 Testa Rossa all&rsquo;asta per Sotheby&rsquo;s, uscita di fabbrica nella primavera del 1958 con le sembianze di una delle auto pi&ugrave; belle di sempre, ha anche una storia &ldquo;personale&rdquo; molto affascinante (e una valutazione decisamente <strong>fuori standard<\/strong>).\n<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/ferrari-gioielli-piu-rari-costosi-sempre\/213165\/#Allasta_una_delle_Ferrari_piu_rare_di_sempre\" title=\"All&rsquo;asta una delle Ferrari pi&ugrave; rare di sempre\">All&rsquo;asta una delle Ferrari pi&ugrave; rare di sempre<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/ferrari-gioielli-piu-rari-costosi-sempre\/213165\/#Testa_Rossa_0738_TR_una_storia_avvincente\" title=\"Testa Rossa 0738 TR: una storia avvincente\">Testa Rossa 0738 TR: una storia avvincente<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Allasta_una_delle_Ferrari_piu_rare_di_sempre\">All&rsquo;asta una delle Ferrari pi&ugrave; rare di sempre<\/span><\/h2>\n<p>La <strong>Testa Rossa &ldquo;Pontoon Fender&rdquo;<\/strong>, con parafango a pontone, &egrave; ampiamente considerata una delle auto pi&ugrave; belle mai realizzate. Non &egrave; un caso se nella presentazione di <strong>RM Sotheby&rsquo;s<\/strong> si fa riferimento alle bellezze del Rinascimento italiano e ai capolavori in grado di &ldquo;<em>trascendere la loro mera presenza di oggetti<\/em>&rdquo; e creare una connessione intima con chiunque li osservi.<\/p>\n<p>La Testa Rossa &egrave; probabilmente la pi&ugrave; grande auto sportiva da corsa mai costruita: come sottolinea Sotheby&rsquo;s, &ldquo;<em>con le Testa Rossa che gareggiavano per la vittoria assoluta mentre le GTO ottenevano vittorie nelle classi GT, si potrebbe affermare che la Testa Rossa &egrave; la Ferrari pi&ugrave; significativa di quell&#8217;epoca d&#8217;oro<\/em>&rdquo;.<\/p>\n<p>Quella che andr&agrave;<strong> all&rsquo;asta a Detroit<\/strong> nei prossimi giorni (l&rsquo;incanto &egrave; previsto per il 21-13 febbraio) &egrave; una vettura straordinariamente preziosa, non soltanto da un punto di vista storico: la Ferrari Testa Rossa 250 &ldquo;Pontoon Fender&rdquo; del 1958 all&rsquo;asta &egrave; <strong>uno dei 19 esemplari<\/strong> con parafango a pontone <a href=\"https:\/\/www.virgilio.it\/motori\/auto\/mitica-ferrari-torna-asta-dopo-oltre-10-anni\/210851\/\">realizzati da Sergio Scaglietti<\/a>. Ma non basta: si tratta anche di una delle pochissime Ferrari Testa Rossa certificata dal Libretto Rosso, e di un&rsquo;auto che ha partecipato a diverse competizioni. Il telaio 0738 TR ha partecipato a <strong>quasi 20 gare d&#8217;epoca<\/strong>, conquistando quattro vittorie assolute in 10 anni di carriera.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Testa_Rossa_0738_TR_una_storia_avvincente\">Testa Rossa 0738 TR: una storia avvincente<\/span><\/h2>\n<p>La storia della Testa Rossa 250 Scaglietti <strong>numero di telaio 0738 TR<\/strong> inizia nella primavera del 1958, quando esce dalle linee di produzione Ferrari per raggiungere il Concessionario Ufficiale Ferrari Centro e Sud America Carlos Kauffman a Caracas, <strong>Venezuela<\/strong>. Il primo proprietario, il brasiliano Jean-Louis Lacerda Soares, la porta subito in pista con la <strong>Scuderia Lagartixa<\/strong>: alla fine del 1960, la Testa Rossa ha gi&agrave; decine di competizioni e diversi podi alle spalle. Nel 1961, l&rsquo;auto viene venduta a Giorgio Moroni, che la fa correre ancora. L&rsquo;ultima competizione della Ferrari 0738 TR risale al 1967.<\/p>\n<p>Dopo<strong> dieci anni di onorata carriera<\/strong>, l&rsquo;auto passa nelle mani dei collezionisti passando per Brasile, Inghilterra e Stati Uniti. Poi, dopo anni passati in deposito, Sir Paul Vestey decide di portarla di nuovo in pista in occasione di eventi come la Mille Miglia e il Goodwood Festival of Speed. Il ritorno ufficiale in competizione (d&rsquo;epoca) avviene sotto la guida di <strong>Carlos Monteverde<\/strong>, che l&#8217;ha guidata in oltre 50 gare, durante la quale viene <strong>coinvolta in due incidenti<\/strong>. Monteverde la ritirer&agrave; dalle gare nel 2010, per affidarla a Ferrari Classiche nel 2013 &#8211; dove sar&agrave; completamente restaurata.<\/p>\n<p>Oggi, la Ferrari Testa Rossa numero di telaio 0738 TR &egrave; &ldquo;<strong>come appena uscita dalla fabbrica<\/strong>&rdquo;. Per questo, l&rsquo;esemplare all&rsquo;asta nei prossimi giorni, una delle Ferrari definitive e &ldquo;<em>il simbolo unico di tutto ci&ograve; che rappresentava Enzo Ferrari<\/em>&rdquo;, ha una valutazione decisamente importante. Il suo valore stimato &egrave; compreso <strong>tra i 34 e i 38 milioni di dollari<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"Sta per andare all\u2019asta per RM Sotheby\u2019s a Detroit una delle Ferrari Testa Rossa pi\u00f9 rare e preziose di sempre: ha partecipato a decine di competizioni","protected":false},"author":183220847,"featured_media":213174,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420889857],"tags":[420890863],"coauthors":[420891354,420891292],"class_list":{"0":"post-213165","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-auto","8":"tag-ferrari","9":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2024\/02\/scaglietti-testa-rossa.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/213165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220847"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=213165"}],"version-history":[{"count":5,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/213165\/revisions"}],"predecessor-version":[{"id":254839,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/213165\/revisions\/254839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/213174"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=213165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=213165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=213165"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=213165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}