{"id":213182,"date":"2024-02-21T09:53:29","date_gmt":"2024-02-21T08:53:29","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=213182"},"modified":"2024-02-21T09:55:05","modified_gmt":"2024-02-21T08:55:05","slug":"superbike-2024-calendario","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/motor-sport\/superbike-2024-calendario\/213182\/","title":{"rendered":"Superbike 2024: si parte in Australia, il calendario"},"content":{"rendered":"<p>Il conto alla rovescia &egrave; cominciato e mancano poche ore all&rsquo;inizio del WorldSBK 2024, il campionato per moto derivate di serie che, come d&rsquo;abitudine, partir&agrave; a Philip Island in Australia dal<strong> 23 al 25 febbraio<\/strong>. La tappa oceanica che vedr&agrave; delinearsi i primi riscontri validi per il titolo di campione del mondo, dopo un lungo inverno passato dai team a fare test, sar&agrave; anche l&rsquo;unica corsa fuori dai confini europei e quindi necessaria per poter omologare questa competizione come mondiale.<\/p>\n<p>Con quasi un mese di distanza da Phillip Island, il circus della Superbike torner&agrave; nel vecchio continente per la seconda gara a Barcellona. Il tracciato del Montmel&oacute; &egrave; da qualche anno in calendario e arricchisce l&rsquo;ispanocentrismo di questa competizione internazionale. Prima delle tre gare spagnole in programma, al circuit de Barcelona-Catalunya vedremo prendere forma il vero volto del campionato.<\/p>\n<p>Ad aprile, tra il 19 e il 21, sar&agrave; la volta di <strong>Assen<\/strong>, la corsa pi&ugrave; a nord di tutta la stagione e tracciato storico per antonomasia. Ad Assen si gareggia dalla notte dei tempi e nonostante i cambiamenti che ha vissuto negli anni, la gara olandese conserva sempre un fascino e una bellezza unica. Vincere ad Assen significa essere indubbiamente uno dei piloti pi&ugrave; forti della storia, tanto che &egrave; chiamata &ldquo;l&rsquo;universit&agrave; della moto&rdquo; e &ldquo;la cattedrale della velocit&agrave;&rdquo;. Il clima intorno all&rsquo;evento &egrave; qualcosa d&rsquo;imperdibile e vale la pena esserci dal vivo.<\/p>\n<p>Una pausa di quasi due mesi e Misano inaugurer&agrave; l&rsquo;estate tra il 14 e il 16 giugno con il primo dei due round italiani. Anche in questo caso, Misano si rivela per i nostri portacolori e per molti team e le marche italiane impegnate la gara di casa. Una festa che come ogni anno si rivela leggendaria e conclude il primo terzo di stagione dove la classifica comincia a prendere quota e capiremo se c&rsquo;&egrave; gi&agrave; qualcuno in fuga verso qualcosa di importante o se saremo davanti ad una lotta serrata per le prime posizioni.<\/p>\n<p>Donington Park fu la sede della prima corsa della Superbike nel 1988 e da allora ha sempre rappresentato la passione di tutto il Regno Unito per questa serie. Nulla di pi&ugrave; tradizionale che andarvi a met&agrave; luglio dove tra il 12 e il 14 non mancheranno le sorprese. Il tracciato inglese &egrave; stato spesso teatro di qualche exploit di wild card locali, ma anche di specialisti del tortuoso saliscendi dell&rsquo;east-midlands. Speriamo che non piova.<\/p>\n<p>A Most qualcuno ha imparato come si guida una moto da oltre trecento all&rsquo;ora nel pi&ugrave; old style dei circuiti. Dal 19 al 21 luglio, il Most Autodrom ospita per la quarta volta il <strong>Gran Premio della Repubblica Ceca<\/strong> di WSBK e come succede spesso da quelle parti, il pubblico ama vivere il weekend in pista gremendo gli spalti e affollando il paddock tra corse, birra, cibo a ciclo continuo e tanta allegria. Posto strategico per i fan della vicina Germania che considerano l&rsquo;evento un po&rsquo; come se fosse il loro GP e giungono in pista con i mezzi pi&ugrave; disparati, ma soprattutto con cos&igrave; tante moto da dover essere parcheggiate in un&rsquo;apposita area ricavata da una pista di atterraggio per elicotteri.<\/p>\n<p>Come spesso accade quando seguiamo la Superbike in Europa, si salta da una parte all&rsquo;altra del continente e dopo una gara all&rsquo;est, ecco che ci catapulteremo all&rsquo;estremo ovest, in Portogallo dove a <strong>Portim&atilde;o<\/strong> potremo goderci il caldo estivo dell&rsquo;Algarve in tutta la sua bellezza. Bellezza anche del circuito che da molti &egrave; stato ribattezzato &ldquo;le montagne russe&rdquo; per la grande variet&agrave; di curve e saliscendi che lo configurano in maniera spettacolare. Effettivamente all&rsquo;Autodromo Internacional do Algarve manca solo il giro della morte delle Hot-Wheels.<\/p>\n<p>Ma il ping-pong degli spostamenti continua e lasciate le sponde dell&rsquo;Atlantico, per il weekend del 23-25 agosto, si ritorna nel cuore d&rsquo;Europa con il Gran Premio d&rsquo;Ungheria che oltre ad essere una novit&agrave; di questa stagione, rappresenta la tappa pi&ugrave; ad est di tutto il calendario. Seconda dopo Most a solcare le terre dell&rsquo;antico blocco orientale, al Balaton Park Circuit si attendono tanti appassionati che da troppo tempo non possono beneficiare di una corsa in casa e di tutte le rappresentanze di motociclisti e fan che giungeranno sulle rive del lago dalla vicina Budapest, ma anche da Slovacchia, Austria e aree circostanti.<\/p>\n<p>Se c&rsquo;&egrave; un luogo che da sempre ha fatto concorrenza al tifo del Mugello dei tempi migliori, questo &egrave; sicuramente il Circuit de Nevers Magny-Cours con i suoi vivaci tifosi che popolano &ldquo;le village&rdquo; in tende, camper, roulotte e per un fine settimana, non lesinano su festeggiamenti h 24. Il clima di Magny-Cours si scalder&agrave; gi&agrave; dalle prime ore della serata del 6 settembre per durare fino a tardi con il gran finale di domenica 8. Da non perdere assolutamente.<\/p>\n<p>La <strong>Francia<\/strong> &egrave; anche il round che inaugura la fase finale del campionato, l&rsquo;ultimo terzo di stagione dove i piloti in lizza per qualcosa di grosso metteranno a segno i propri colpi. Dal 20 al 22 settembre si scender&agrave; in Italia e pi&ugrave; precisamente al <a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/mondiale-superbike-cremona-nel-2024\/207017\/\">Cremona Circuit<\/a> che debutta come location del motociclismo che conta e di questo sport, ai massimi livelli. Ci sono grandi aspettative per un tracciato che fino alla fine del prossimo settembre avr&agrave; ospitato solo campionati minori, ma non per questo meno importanti da un punto di vista logistico, tecnico e intrattenitore. C&rsquo;&egrave; molta curiosit&agrave; e voglia che questa nuova oasi delle corse si consolidi per il futuro.<\/p>\n<p>Il rush finale del campionato &egrave; formato da una <strong>doppietta di gare in Spagna.<\/strong> Si torna quindi nella Penisola Iberica per attraversarla da parte a parte. Se dal 27 al 29 settembre la Superbike sar&agrave; al Motorland di Aragon, pista moderna e apprezzata da tanti piloti molto veloci sui tracciati tecnici, l&rsquo;ultima gara si correr&agrave; a Jerez de la Frontera, uno dei luoghi storici, dove il tempo sembra essersi fermato e nella calda Andalusia, il cronometro dei tempi segna le giornate come il sole che cala tardi anche a ottobre inoltrato. L&rsquo;auspicio &egrave; godersi lo spettacolo anche nel weekend del 18-20 ottobre per assaporare fino all&rsquo;ultima curva ogni momento di quella che si preannuncia una della annate pi&ugrave; ricche e speriamo gloriose, di sempre.<\/p>\n","protected":false},"excerpt":{"rendered":"Il campionato per moto derivate di serie che, come d\u2019abitudine, partir\u00e0 a Philip Island in Australia dal 23 al 25 febbraio.","protected":false},"author":183220727,"featured_media":207034,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420891318],"tags":[420891230],"coauthors":[420891188,420891185],"class_list":{"0":"post-213182","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-motor-sport","8":"tag-superbike","9":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2023\/11\/suprbike.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/213182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220727"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=213182"}],"version-history":[{"count":7,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/213182\/revisions"}],"predecessor-version":[{"id":254180,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/213182\/revisions\/254180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/207034"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=213182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=213182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=213182"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=213182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}