{"id":217797,"date":"2024-03-20T09:10:50","date_gmt":"2024-03-20T08:10:50","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=217797"},"modified":"2024-03-20T12:17:36","modified_gmt":"2024-03-20T11:17:36","slug":"pedalare-smog-studio-effetti","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/smart-mobility\/pedalare-smog-studio-effetti\/217797\/","title":{"rendered":"Pedalare nello smog, uno studio sugli effetti"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Sportivi e non solo se lo chiedono spesso: <strong>ma l\u2019attivit\u00e0 fisica in mezzo allo smog \u00e8 dannosa?<\/strong> Qual \u00e8 il rapporto rischi\/benefici dello sport leggero praticato dentro una citt\u00e0? \u00c8 importante saperlo soprattutto oggigiorno e soprattutto nel <strong>nord-Italia<\/strong>, una delle aree pi\u00f9 inquinate d\u2019Europa. Le nubi di polveri sottili che colpiscono sempre pi\u00f9 spesso la pianura padana hanno provocato giustificati appelli alla cautela per chi vive in quei luoghi. Tuttavia non bisogna farsi prendere dal panico e per queste ragioni rinunciare a muoversi, alternativa estremamente peggiore dal punto di vista della salute. Uno<strong> studio condotto congiuntamente da diverse universit\u00e0 nel mondo<\/strong> chiarisce meglio un dubbio che attanaglia da sempre diverse persone.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Tra i diretti interessati ci sono sicuramente i <strong>ciclisti urbani<\/strong> che, soprattutto nelle citt\u00e0 meno pianeggianti, tendono a <strong>ventilare con pi\u00f9 frequenza e pi\u00f9 in profondit\u00e0<\/strong>. Subito dopo troviamo corridori, <strong>scooteristi<\/strong> e semplici <strong>pedoni<\/strong>, anche loro esposti ai malsani miasmi delle nostre metropoli. E non si salvano nemmeno gli automobilisti. Non pensiate infatti che muoversi in un abitacolo sia tanto meglio: tenere i finestrini aperti o far circolare l\u2019aria attraverso l\u2019impianto di condizionamento \u00e8 soltanto <strong>leggermente meno dannoso<\/strong>. <\/span><span style=\"font-weight: 400\"><strong>Pedalare nello smog<\/strong> per\u00f2, tende giustamente a preoccupare tutti quei ciclisti che usano la bici quotidianamente. Compiere dei respiri a pieni polmoni in mezzo ai tubi di scarico non sembra una pratica molto sana e non \u00e8 chiaro se in qualche modo venga compensata dai benefici dell\u2019attivit\u00e0 fisica in s\u00e9.<\/span><\/p>\n<h2><b>Lo studio\u00a0<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Secondo uno <\/span><b>studio<\/b><span style=\"font-weight: 400\"> condotto congiuntamente da diverse universit\u00e0 nel mondo, i vantaggi dell\u2019attivit\u00e0 fisica in un contesto urbano superano i danni provocati dal relativo inquinamento, tranne quando questo \u00e8 presente in modo estremamente elevato.\u00a0<\/span><br \/>\n<span style=\"font-weight: 400\">Nell\u2019analisi sono stati considerati <strong>due scenari<\/strong> di massima, il primo in cui le concentrazioni di particolato PM2,5 si attestavano intorno ai<strong> 22 \u03bcg\/m3<\/strong>, il secondo con invece livelli altissimi, e cio\u00e8 oltre i <strong>100 \u03bcg\/m3<\/strong>.\u00a0<\/span><br \/>\n<span style=\"font-weight: 400\">E\u2019 stata poi analizzata la mortalit\u00e0 in base allo scenario, verificando se un\u2019attivit\u00e0 fisica come pedalare o camminare fino a 16 ore al giorno influenzasse in qualche modo il risultato.\u00a0<\/span><br \/>\n<span style=\"font-weight: 400\">Nel caso del <strong>primo scenario<\/strong>, quello pi\u00f9 diffuso secondo una media mondiale, i benefici dell&#8217;attivit\u00e0 fisica superano di gran lunga i rischi derivanti dall&#8217;inquinamento atmosferico, anche nei casi di fatica pi\u00f9 intensa. Possiamo perci\u00f2 stare tranquilli, <strong>il rapporto rischi\/benefici pone a favore dei secondi<\/strong>.<\/span><br \/>\n<span style=\"font-weight: 400\">Invece, nelle aree con una concentrazione costante di PM2,5 di 100 \u03bcg\/m3, <strong>i danni supererebbero i vantaggi solo dopo 1 ora e 30 minuti di bicicletta al giorno o pi\u00f9 di 10 ore di camminata<\/strong>, tempi in ogni caso molto distanti dalla media dei normali spostamenti urbani. Secondo l\u2019OMS, le citt\u00e0 con un simile livello di concentrazione sono per fortuna poche, ma le cose stanno peggiorando rapidamente, soprattutto in Pianura padana (l\u2019area pi\u00f9 inquinata d\u2019Europa) e in particolare a Milano.\u00a0<\/span><\/p>\n<h2><b>I consigli della Fondazione Veronesi<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Non si tratta di una vera e propria novit\u00e0; questo studio \u00e8 solo una conferma di altri dati scientifici disponibili e che da diverso tempo vengono diffusi. La Fondazione Veronesi ad esempio dice chiaramente che <strong>lo smog non \u00e8 una buona ragione per evitare di fare attivit\u00e0 fisica all\u2019aperto<\/strong> e d\u00e0 alcuni consigli, tanto banali quanto efficaci, per praticarla in sicurezza:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">informarsi sulla <strong>qualit\u00e0 dell\u2019aria<\/strong> prima di eseguire sport all\u2019aperto;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">evitare il traffico e cercare <strong>aree verdi<\/strong>;<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">indossare una <strong>mascherina per passeggio<\/strong> o nei tratti di spostamento.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Noi aggiungiamo di tenere in considerazione anche i <strong>filtri nasali<\/strong> che permettono di inspirare dal naso aria filtrata ma, se dovesse essercene bisogno, di fare anche delle inalazioni dalla bocca.<\/span><br \/>\n<span style=\"font-weight: 400\">Stare sul divano \u00e8 quindi molto peggio, tanto che ormai si dice che <strong>stare seduti sia il nuovo fumare<\/strong>. La vita sedentaria porta ad una serie di problemi non facilmente individuabili nell\u2019immediato ma che possono diventare gravi in brevissimo tempo. Certo, quando le polveri sottili sono troppo elevate e la percezione del respiro comincia a farsi davvero pesante bisogna assolutamente preferire l\u2019indoor. Con l\u2019arrivo della stagione calda questi fenomeni saranno purtroppo <strong>pi\u00f9 frequenti<\/strong> ed \u00e8 importante avere coscienza su come comportarsi.<\/span><\/p>\n<h2><b>Perch\u00e9 scegliere l\u2019e-bike<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Riassumendo quindi possiamo tranquillamente pedalare in citt\u00e0, <strong>ci far\u00e0 comunque meglio che stare fermi in automobile o chiusi in casa<\/strong>, dove anzi perdiamo l\u2019occasione di compensare ai danni dell\u2019aria cattiva attraverso dell\u2019attivit\u00e0 fisica. Certo, se ci troviamo in bici al centro di Pechino o quando ci sono specifici appelli alla cautela, magari evitiamo di darci dentro per due ore proprio in mezzo al traffico, ma in tutti gli altri casi ci far\u00e0 solo che bene. <\/span><span style=\"font-weight: 400\">L\u2019inquinamento ormai \u00e8 ovunque e presente in diverse forme, quello che possiamo fare \u00e8 soprattutto <strong>evitare di innalzare i livelli di PM2,5, anche attraverso l\u2019uso della bici<\/strong>: \u00e8 stato infatti dimostrato che l\u2019utilizzo di questo veicolo incide molto sullo smog a livello locale, contrastando l\u2019azione dannosa delle cosiddette isole di calore. <\/span><\/p>\n<p><span style=\"font-weight: 400\">I modelli a <strong>pedalata assistita<\/strong> poi, sembrano particolarmente vantaggiosi in questo senso, sia perch\u00e9 riducono la circolazione di mezzi pi\u00f9 pesanti, sia perch\u00e9 permettono una respirazione meno affannosa a cui \u00e8 possibile associare dispositivi di protezione leggeri. In un nostro precedente <\/span><a href=\"https:\/\/www.virgilio.it\/motori\/smart-mobility\/traffico-smog-ciclisti-scooteristi-possono-difendersi\/210362\/\"><span style=\"font-weight: 400\">articolo<\/span><\/a><span style=\"font-weight: 400\"> abbiamo parlato proprio di questo tema e vi rimandiamo a lui per maggiori dettagli; vale per\u00f2 la pena ricordare anche qui che mascherine sportive e filtri nasali devono essere utilizzati con la massima attenzione.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Se quindi siete ciclisti urbani o avete intenzione di diventarlo, considerate l\u2019utilizzo di una <strong>bici elettrica a pedalata assistita<\/strong>: farete del bene alla vostra citt\u00e0, al pianeta, e anche a voi stessi.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"Chi va in bici in citt\u00e0 o pratica attivit\u00e0 fisica presso aree particolarmente inquinate si domanda spesso se non faccia male, vediamo se \u00e8 davvero cos\u00ec","protected":false},"author":183220814,"featured_media":217800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420891086],"tags":[420890823],"coauthors":[420891314,420891312],"class_list":{"0":"post-217797","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-smart-mobility","8":"tag-divieti-di-circolazione","9":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2024\/03\/Bici-smog.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/217797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220814"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=217797"}],"version-history":[{"count":3,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/217797\/revisions"}],"predecessor-version":[{"id":217905,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/217797\/revisions\/217905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/217800"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=217797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=217797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=217797"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=217797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}