{"id":222835,"date":"2024-04-17T09:20:52","date_gmt":"2024-04-17T07:20:52","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=222835"},"modified":"2024-04-18T10:18:43","modified_gmt":"2024-04-18T08:18:43","slug":"telepass-canone-piu-caro-crescono-servizi","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/notizie\/telepass-canone-piu-caro-crescono-servizi\/222835\/","title":{"rendered":"Telepass, canone pi\u00f9 caro, ma crescono i servizi"},"content":{"rendered":"<p>Il <strong>Telepass<\/strong> \u00e8 diventato uno strumento vitale per chi vive l&#8217;autostrada con frequenza, ma non solo. Quel piccolo blocchettino capace di alzare la sbarra quando un veicolo passa attraverso il casello autostradale evita di saltare code e file, e si \u00e8 rivelato un amico per chi non vuole sprecare del tempo prezioso. A partire dall&#8217;estate questo strumento subir\u00e0 un <strong>rincaro<\/strong>, che sar\u00e0 <strong>attivo a partire dal 1\u00b0 luglio 2024.\u00a0<\/strong>Il nuovo posizionamento sul mercato \u00e8 un fattore naturale, anche perch\u00e9 questo dispositivo promette di offrire alcuni servizi in pi\u00f9 rispetto al recente passato, oltre a 4 pacchetti differenti tra i quali scegliere.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/telepass-canone-piu-caro-crescono-servizi\/222835\/#Il_rincaro_di_Telepass\" title=\"Il rincaro di Telepass\">Il rincaro di Telepass<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/telepass-canone-piu-caro-crescono-servizi\/222835\/#I_nuovi_pacchetti_di_Telepass\" title=\"I nuovi pacchetti di Telepass\">I nuovi pacchetti di Telepass<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Il_rincaro_di_Telepass\">Il rincaro di Telepass<\/span><\/h2>\n<p>Dunque, a partire dal primo luglio 2024\u00a0 il <strong>canone Base coster\u00e0 3,90 euro al mese.<\/strong> Prima era chiamato Family e costava 1,83 euro al mese. Il rincaro \u00e8 quindi del +113%, e dai vertici dell&#8217;azienda spiegano che \u00e8 necessario poich\u00e9 \u00e8 <em>&#8220;mutato il contesto di mercato e tecnologico e avendo maturato la consapevolezza di disporre di un\u2019esperienza, di un\u2019offerta e di una capacit\u00e0 di innovazione uniche sul mercato&#8221;. <\/em>Il Gruppo Mundys decide di <a href=\"https:\/\/www.virgilio.it\/motori\/info-utili\/video\/pedaggi-autostradali-ecco-la-novita-che-aumenta-la-concorrenza\/178041\/\">differenziarsi rispetto a Unipol Move<\/a>, un concorrente entrato sul mercato due anni fa.<\/p>\n<p>L&#8217;obiettivo \u00e8 quello di avere una\u00a0<em>&#8220;nuova proposizione commerciale che valorizzi al meglio, anche in prospettiva, l\u2019ecosistema della propria offerta consumer e punti, al contempo, a offrire soluzioni sempre all\u2019avanguardia per le necessit\u00e0 di movimento della propria clientela in ambito urbano&#8221;, <\/em>dichiarano dal Gruppo Mundys. Rispetto ai competitors, Telepass fa valere<strong> l&#8217;ampiezza del proprio sistema fortificato negli anni<\/strong>. In un mercato in profondo e continuo cambiamento, tenta di monetizzare la propria esperienza e i propri vantaggi competitivi.<\/p>\n<p>&#8220;<em>Il nuovo posizionamento di mercato cambia il paradigma: il telepedaggio diventa solo uno, ma non il principale, dei servizi dell\u2019ecosistema di Telepass, volto ad <strong>abilitare una mobilit\u00e0 integrata<\/strong> e sempre pi\u00f9 sostenibile, intorno alla persona, e focalizzata sui centri urbani<\/em>&#8220;, dice la nota stampa di Telepass.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"I_nuovi_pacchetti_di_Telepass\">I nuovi pacchetti di Telepass<\/span><\/h2>\n<p>Dal primo di luglio Telepass cambia e stravolge i propri pacchetti: uno a consumo e tre in abbonamento. Cambiano anche i servizi offerti, che diventano pi\u00f9 ricchi:<\/p>\n<p><strong>Telepass Pay per Use<\/strong>\u00a0(a consumo):<\/p>\n<ul>\n<li>attivazione <strong>10 euro + 1 euro ogni giorno di effettivo utilizzo<\/strong><\/li>\n<li>Area C Milano<\/li>\n<li>Traghetto stretto di Messina<\/li>\n<li>Parcheggi convenzionati<\/li>\n<li>Strisce Blu<\/li>\n<li>Vignette elettroniche autostrade<\/li>\n<\/ul>\n<p><strong>Telepass Base<\/strong>:<\/p>\n<ul>\n<li>3,90 euro al mese, attivazione inclusa e possibilit\u00e0 di associare due targhe<\/li>\n<li><a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/pagamento-pedaggi-autostrada-come-saltare-coda-caselli\/195854\/\">Telepedaggio<\/a><\/li>\n<li><strong>Area C Milano<\/strong><\/li>\n<li>Traghetto stretto di Messina<\/li>\n<li>Parcheggi convenzionati<\/li>\n<li>Strisce Blu<\/li>\n<li>Vignette elettroniche autostrade<\/li>\n<\/ul>\n<p><strong>Telepass Plus<\/strong>:<\/p>\n<ul>\n<li>3,90 euro al mese in promo fino a dicembre 2025, poi 4,90 euro al mese, attivazione inclusa e possibilit\u00e0 di associare due targhe<\/li>\n<li>Area C Milano<\/li>\n<li>Traghetto stretto di Messina<\/li>\n<li>Parcheggi convenzionati<\/li>\n<li><strong>Strisce Blu<\/strong><\/li>\n<li>Vignette elettroniche autostrade<\/li>\n<li>Carburante<\/li>\n<li>Ricarica auto elettrica<\/li>\n<li><strong>Skipass<\/strong><\/li>\n<li>Trasporto pubblico<\/li>\n<li>Treni<\/li>\n<li>Voli<\/li>\n<li>Altri servizi per un totale di 25<\/li>\n<\/ul>\n<p><strong>Telepass Young<\/strong>:<\/p>\n<ul>\n<li>dettagli ancora da comunicare<\/li>\n<li><strong>Niente telepedaggio<\/strong><\/li>\n<li>Trasporto pubblico<\/li>\n<li>Mobilit\u00e0 condivisa<\/li>\n<li>Treni<\/li>\n<li>Voli<\/li>\n<li>Pullman.<\/li>\n<\/ul>\n<p>Telepass Young \u00e8 una delle novit\u00e0 pi\u00f9 gustose, perch\u00e9 pensata per i pi\u00f9 giovani e che non hanno dimestichezza con i mezzi privati. Il prezzo \u00e8 ancora da calibrare e verr\u00e0 mostrato nelle prossime settimane, ma sicuramente non ci sar\u00e0 un canone. Si attiver\u00e0<strong> tramite carta di credito<\/strong> o di debito e includer\u00e0 i principali servizi legati alla mobilit\u00e0 presenti nella piattaforma Telepass.<\/p>\n","protected":false},"excerpt":{"rendered":"Telepass vara una piccola rivoluzione per continuare a essere leader del mercato, quindi aumentano i costi mensili ma crescono tutti i servizi","protected":false},"author":183220833,"featured_media":222843,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[25915],"tags":[420890880,420891390],"coauthors":[420891333,420891331],"class_list":{"0":"post-222835","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-notizie","8":"tag-autostrade","9":"tag-telepass-e-pedaggi-autostradali","10":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2024\/04\/Telepass-aumentano-le-tariffe.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/222835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220833"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=222835"}],"version-history":[{"count":3,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/222835\/revisions"}],"predecessor-version":[{"id":222901,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/222835\/revisions\/222901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/222843"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=222835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=222835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=222835"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=222835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}