{"id":225556,"date":"2024-05-20T17:00:12","date_gmt":"2024-05-20T15:00:12","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=225556"},"modified":"2024-06-25T09:35:10","modified_gmt":"2024-06-25T07:35:10","slug":"mclaren-artura-ibrida","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/auto\/mclaren-artura-ibrida\/225556\/","title":{"rendered":"McLaren Artura Spider, prima decappottabile ibrida ad alte prestazioni"},"content":{"rendered":"<p>La <strong>McLaren Artura<\/strong> perde la testa\u2026 letteralmente con la <strong>versione Spider<\/strong>. E la perdere anche ai fan, con una delle sue produzioni pi\u00f9 lussuose e impattanti sotto il profilo estetico. Dopo la coup\u00e9, nei selezionati rivenditori del marchio di Woking \u00e8 disponibile pure la variante cabrio, <strong>svelata a Londra presso il prestigioso Outernet<\/strong>, l&#8217;attrazione turistica pi\u00f9 visitata della capitale inglese lo scorso anno. Che conferma le straordinarie propriet\u00e0 artigianali della Casa, una delle poche a dare vero filo da torcere alle giganti italiane.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/mclaren-artura-ibrida\/225556\/#Hardtrop_azionabile_in_11_secondi\" title=\"Hardtrop azionabile in 11 secondi\">Hardtrop azionabile in 11 secondi<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/mclaren-artura-ibrida\/225556\/#Interni_e_prezzi\" title=\"Interni e prezzi\">Interni e prezzi<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Hardtrop_azionabile_in_11_secondi\">Hardtrop azionabile in 11 secondi<\/span><\/h2>\n<p>Subito l\u2019occhio cade sull\u2019<strong>hardtop retrattile in fibra di carbonio<\/strong>, azionabile elettricamente in soli 11 secondi. Rispetto alla tela o al tetto a soffietto, presenta diversi vantaggi, tra cui la maggiore sicurezza e il miglior isolamento acustico. Sottoposte a un aggiornamento stilistico, le prese d\u2019aria vantano un raffreddamento e un\u2019aerodinamica eccellenti. Le temperature di esercizio rimangono su valori corretti, essenziale nel caso di un bolide che richiede un lavoro efficiente per mantenere potenza e affidabilit\u00e0.<\/p>\n<p>In virt\u00f9 dell\u2019aerodinamica curata in modo scrupoloso, la <a href=\"https:\/\/www.virgilio.it\/motori\/listino\/mclaren\/mclaren-artura\/\">McLaren Artura<\/a> Spider (<a href=\"https:\/\/www.virgilio.it\/motori\/auto\/fotonotizia\/mclaren-artura-spider-esaltante-scoperta-700-cv\/213845\/\">gi\u00e0 mostrata nei minimi dettagli<\/a>) brilla nella velocit\u00e0 e nell\u2019accelerazione, a fronte di consumi di carburante limitati. Le <strong>portiere ad ali di gabbiano<\/strong> contribuiscono all\u2019aspetto aggressivo e futuristico, a rimarcarne il carattere da supercar. Inoltre, facilitano l\u2019ingresso nell\u2019abitacolo, soprattutto a persone alte o dalla mobilit\u00e0 ridotta. I <strong>cerchi in lega neri da 15 razze<\/strong> hanno un look sportivo che esalta il colpo d\u2019occhio complessivo. Dietro sono visibili i<strong> freni in carbonio-ceramica<\/strong>, segno delle elevate performance.<\/p>\n<p>Migliora la stabilit\u00e0 e l\u2019aerodinamica lo <strong>spoiler posteriore<\/strong>, essenziale alle alte velocit\u00e0. \u00c8 proposto a un altro scopo il <strong>lunotto posteriore riscaldato<\/strong>: assicurare il relax degli occupanti. Nella circolazione in giornate calde o umide, favorisce una visibilit\u00e0 chiara e sicura, importante soprattutto per la retromarcia, in maniera da evitare incidenti.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Interni_e_prezzi\">Interni e prezzi<\/span><\/h2>\n<p>Nel pacchetto di serie, la scoperta della <a data-doctype=\"\" href=\"https:\/\/www.virgilio.it\/motori\/listino\/mclaren\/\" rel=\"noopener\" target=\"_blank\">gamma McLaren<\/a> ha<strong> sedili McLaren Clubsport<\/strong>, che offrono comfort e supporto. Previo pagamento di un extra, \u00e8 possibile adottarli riscaldati e regolabili elettricamente con memoria. In generale, il salotto \u00e8 incentrato sull\u2019automobilista con volante \u201cpulito\u201d privo di pulsanti.<\/p>\n<p>Una coppia di display ad alta definizione (HD) contraddistingue il sistema di infotainment McLaren (MIS). Immergersi nell\u2019atmosfera \u00e8 questione di un attimo: il tempo di accendere l\u2019<strong>impianto audio a cinque altoparlanti di serie<\/strong>. Su richiesta, \u00e8 disponibile un equipaggiamento surround Bowers &amp; Wilkins a 12 altoparlanti. Sul fronte della protezione, le numerose funzioni ADAS rappresentano un prezioso strumento ausiliare alla guida.<\/p>\n<p>Riceve un aumento di 20 CV, per un totale di 700 CV e 720 Nm di coppia, il <strong>powertrain ibrido<\/strong>, ricalibrato su misura. I nuovi supporti mirano sia a un controllo ottimale del gruppo propulsore sia a una guida pi\u00f9 precisa. In abbinamento, la potenza viene trasmessa alle ruote dal cambio a otto rapporti, rapido e fluido negli innesti. Il sistema di scarico sportivo opzionale enfatizza la \u201cmelodia\u201d del motore.<\/p>\n<p>La McLaren Artura Spider scatta <strong>da 0 a 100 km\/h in 3,0 secondi<\/strong>, i 200 in 8,4 secondi e i 300 km\/h in 21,6 secondi, mentre la velocit\u00e0 massima \u00e8 di 330 km\/h. Il listino prezzi parte da 276.550 euro (IVA inclusa). Coperta da garanzia di cinque anni a chilometraggio illimitato, prevede tre ulteriori specifiche per gli interni, ciascuna dal costo di 9.950 euro.<\/p>\n","protected":false},"excerpt":{"rendered":"La McLaren Artura Spider si mostra a Londra in una cornice da grandi occasioni quale Outernet: \u00e8 la prima decappottabile ibrida ad alte prestazioni","protected":false},"author":183220841,"featured_media":225564,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420889857],"tags":[420890797,420890825],"coauthors":[420891349,420891347],"class_list":{"0":"post-225556","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-auto","8":"tag-auto-ibride","9":"tag-spider","10":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2024\/05\/McLaren-Artura-Spider-presentazione.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/225556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220841"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=225556"}],"version-history":[{"count":2,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/225556\/revisions"}],"predecessor-version":[{"id":232110,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/225556\/revisions\/232110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/225564"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=225556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=225556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=225556"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=225556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}