{"id":226908,"date":"2024-06-01T11:23:40","date_gmt":"2024-06-01T09:23:40","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=226908"},"modified":"2024-06-01T11:32:45","modified_gmt":"2024-06-01T09:32:45","slug":"furti-auto-25-secondi-kia-boys","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/curiosita\/furti-auto-25-secondi-kia-boys\/226908\/","title":{"rendered":"Furti d&#8217;auto in soli 25 secondi: impazza la banda dei Kia Boys"},"content":{"rendered":"<p>Rubare un\u2019auto in 25 secondi. \u00c8 la nuova allarmante sfida che imperversa su TikTok, messa a segno da giovani protagonisti, disposti a tutto pur di diventare popolari. Alla prospettiva di un \u201cpieno\u201d di visualizzazioni, imperversano sulle strade con le Kia e le Hyundai prodotte tra il 2011 e il 2021 nel mirino . Sfruttano una falla del sistema e con velocit\u00e0 fulminea superano gli impianti di sicurezza realizzati dalle Case. <strong>Gi\u00e0 ribattezzati Kia Boys<\/strong>, i ladri rompono il finestrino, accendono la vettura usando un cacciavite e poi sfrecciano via.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/curiosita\/furti-auto-25-secondi-kia-boys\/226908\/#I_pericoli\" title=\"I pericoli\">I pericoli<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/curiosita\/furti-auto-25-secondi-kia-boys\/226908\/#Come_difendersi\" title=\"Come difendersi\">Come difendersi<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"I_pericoli\">I pericoli<\/span><\/h2>\n<p>Lo stile avventato al volante spesso provoca incidenti e danni a persone e cose. <strong>La maggior parte dei responsabili sono minorenni<\/strong>, attratti dalla sfida e dal desiderio di fama online. Mettono a repentaglio la loro stessa incolumit\u00e0 e quella altrui, attraverso manovre spericolate e illegali, da condannare a priori. Rispetto agli anni precedenti, il numero dei furti registrato dalle Forze dell\u2019Ordine \u00e8 aumentato e non sembrano rallentare.<\/p>\n<p>Oltre ai problemi di natura materiale, i proprietari delle auto sottratte in modo indebito subiscono il disagio di rimanere senza mezzo di trasporto. Le riparazioni possono essere costose, soprattutto se la macchina finisce coinvolta in un incidente. La collaborazione tra cittadini, Forze dell\u2019Ordine e Costruttori serve a contrastare il fenomeno, purtroppo in via di diffusione oltreoceano. In cima alle priorit\u00e0 devono esserci la sicurezza stradale, la stessa ragione perseguita con lo <a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/luglio-stop-vendita-auto-senza-questi-dispositivi\/221232\/\">stop alla vendita delle auto senza certi dispositivi<\/a>, e la tutela dei singoli individui.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Come_difendersi\">Come difendersi<\/span><\/h2>\n<p>Per contrastare il fenomeno, le Case produttrici hanno <strong>rilasciato una patch antifurto<\/strong>, fondamentale a scopo protettivo. Competere ai legittimi proprietari accertarsi se il modello \u00e8 interessato ed eseguire l\u2019installazione. Il montaggio di un bloccasterzo o di un sistema di allarme aggiuntivo pu\u00f2 dissuadere i ladri e incrementare le chance di recupero.\u00a0Sul mercato non mancano dei validi accessori, anche di ottima qualit\u00e0. In circostanze simili \u00e8 il caso di mettere il risparmio in secondo piano. Infatti, capita di imbattersi in articoli venduti a prezzi irrisori, ma pressoch\u00e9 vani, facilmente scardinabili da chi ha un minimo di dimestichezza.<\/p>\n<p>Alcuni guidatori hanno poi iniziato a utilizzare un <strong>\u201cblock shaft\u201d con allarme o antifurti satellitari<\/strong>, in grado di segnalare il movimento della vettura e avvertire il proprietario in presenza di allarme. Per contenere la spesa, pu\u00f2 essere una buona idea valutare l&#8217;acquisto in rete, tramite le piattaforme e-commerce. Sul web vi \u00e8 di solito modo di consultare le recensioni dei clienti, in maniera da farsi un&#8217;idea sulla qualit\u00e0 di un determinato tipo di prodotto e andare, perci\u00f2, sul sicuro.<\/p>\n<p>Inoltre, un dispositivo come<strong> l\u2019AirTag di Apple<\/strong> \u00e8 potenzialmente efficace nel rintracciare l\u2019auto rubata e a favorire il lavoro delle autorit\u00e0. In caso di furto, si raccomanda di denunciare il fatto agli organi di competenza il prima possibile, fornendo ogni informazione utile. Al momento, non si registrano episodi simili in Italia e ci auguriamo la situazione rimanga cos\u00ec. Con una pena detentiva da un minimo di due a un massimo di sei anni, la legge considera il furto d\u2019auto un reato grave. Al trasgressore il giudice pu\u00f2 anche comminare il risarcimento dei danni e delle spese legali alla parte lesa.<\/p>\n","protected":false},"excerpt":{"rendered":"I Kia Boys terrorizzano le strade degli USA: in soli 25 secondi, riescono a rubare modelli Kia e Hyundai. Le loro &#8220;prodezze&#8221; sono virali su TikTok","protected":false},"author":183220841,"featured_media":226916,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420890037],"tags":[420890871,420890961],"coauthors":[420891349,420891347],"class_list":{"0":"post-226908","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-curiosita","8":"tag-hyundai","9":"tag-kia","10":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2024\/06\/Kia-Boys-sfida-virale-1.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/226908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220841"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=226908"}],"version-history":[{"count":3,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/226908\/revisions"}],"predecessor-version":[{"id":226919,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/226908\/revisions\/226919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/226916"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=226908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=226908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=226908"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=226908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}