{"id":227009,"date":"2024-06-02T12:51:01","date_gmt":"2024-06-02T10:51:01","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=227009"},"modified":"2024-06-25T10:32:24","modified_gmt":"2024-06-25T08:32:24","slug":"smart-fortwo-truffa-usato","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/notizie\/smart-fortwo-truffa-usato\/227009\/","title":{"rendered":"Smart Fortwo, \u00e8 boom di truffe sul mercato dell&#8217;usato"},"content":{"rendered":"<p>La <strong>Smart Fortwo<\/strong> \u00e8 uscita di produzione dopo 25 anni di onorata carriera: nonostante ci\u00f2, sono tanti gli italiani che rimpiangono un modello cos\u00ec iconico, amato soprattutto per via della sua estrema compattezza e maneggevolezza, due qualit\u00e0 che permettono di parcheggiarla praticamente ovunque.<\/p>\n<p>Finita la produzione ufficiale, sono aumentate in modo considerevole le richieste di <a href=\"https:\/\/www.virgilio.it\/motori\/listino\/smart\/smart-fortwo\/\">Smart Fortwo<\/a> di seconda mano, diventata una delle auto pi\u00f9 richieste nel mercato dell&#8217;usato. A fronte di un incremento della domanda, sono aumentati anche i <strong>rischi<\/strong> per chi intende acquistarle.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/smart-fortwo-truffa-usato\/227009\/#Smart_Fortwo_di_seconda_mano_aumenta_la_richiesta\" title=\"Smart Fortwo di seconda mano: aumenta la richiesta\">Smart Fortwo di seconda mano: aumenta la richiesta<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/smart-fortwo-truffa-usato\/227009\/#Cosa_controllare_prima_di_acquistare_unauto_usata\" title=\"Cosa controllare prima di acquistare un\u2019auto usata\">Cosa controllare prima di acquistare un\u2019auto usata<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Smart_Fortwo_di_seconda_mano_aumenta_la_richiesta\">Smart Fortwo di seconda mano: aumenta la richiesta<\/span><\/h2>\n<p><strong>Carfax<\/strong>, nota piattaforma di informazioni sulla storia delle vetture usate, ha condotto un&#8217;indagine per determinare quali sono i maggiori pericoli per chi \u00e8 intenzionato a comprare una Smart Fortwo usata, e a cosa bisogna prestare attenzione prime di precedere con l&#8217;acquisto.<\/p>\n<p>Secondo i dati di Carfax che risalgono a gennaio 2023, le Fortwo attualmente <a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/incentivi-novita-svecchiare-parco-auto\/197603\/\">in circolazione in Italia<\/a> hanno un&#8217;et\u00e0 media di 11 anni e hanno percorso mediamente 89.000 chilometri. Per la piattaforma, una delle prime informazioni da controllare quando si vuole acquistare una Smart (ma la regola vale per qualsiasi modello) \u00e8 quella relativa al numero di proprietari.<\/p>\n<p>L&#8217;indagine rivela che solamente il 15% delle Fortwo italiane pu\u00f2 vantare un unico proprietario, mentre per il 54% dei modelli circolanti i <strong>proprietari<\/strong> precedenti sono stati tra i due e i quattro, e per il 29% addirittura cinque o pi\u00f9. Gli esemplari per i quali non c&#8217;\u00e8 stato nessun passaggio di propriet\u00e0 sono davvero pochi e questo \u00e8 un elemento che potrebbe incidere sui fattori di rischio al momento dell&#8217;acquisto.<\/p>\n<p>Stando all&#8217;analisi di Carfax, il 40% delle Smart Fortwo in Italia presenta almeno un fattore di rischio, quando la media per le altre auto circolanti nel nostro Paese non supera il 26%. Il problema pi\u00f9 diffuso tra le mitiche compatte \u00e8 quello di aver avuto un <strong>incidente stradale<\/strong> o un danno di vario tipo: elemento comune al 29% dei modelli circolanti: qualora l&#8217;auto non fosse stata riparata in maniera adeguata, potrebbe rappresentare un potenziale pericolo per la sicurezza, sia delle persone a bordo che di tutti gli utente della strada.<\/p>\n<p>Il 9% delle Smart Fortwo che si trovano sulle strade italiane, inoltre, \u00e8 di provenienza estera, mentre il 5% risulta &#8220;schilometrato&#8221;, ci\u00f2 significa che presenta un <a href=\"https:\/\/www.virgilio.it\/motori\/info-utili\/come-si-azzera-il-contachilometri-dellauto\/84161\/\">contachilometri alterato<\/a> per far apparire minore il numero totale di chilometri percorsi dal veicolo: altro fattore da tenere in considerazione quando si intende acquistare un&#8217;auto usata.<\/p>\n<p>Sul <a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/gennaio-2024-italia-vola-mercato-usato\/212713\/\">mercato delle vetture di seconda mano<\/a>, l&#8217;et\u00e0 pu\u00f2 fare una grande differenza, sulla qualit\u00e0 e automaticamente anche sul prezzo e a tal proposito Carfax rivela che nelle Smart Fortwo pi\u00f9 recenti, non pi\u00f9 vecchie di 5 anni, solo l&#8217;11% presenta un fattore di rischio: in pratica circa una su dieci, una media buona per un&#8217;auto cos\u00ec richiesta.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Cosa_controllare_prima_di_acquistare_unauto_usata\">Cosa controllare prima di acquistare un\u2019auto usata<\/span><\/h2>\n<p>Per Marco Arban, direttore del Business Development in Europa di Carfax in Europa, le Smart Fortwo usate presentano un <strong>fattore di rischio<\/strong> superiore rispetto alla media di altre vetture in Italia:<\/p>\n<p>&#8220;Dai dati in nostro possesso emerge come questa city car presenti un numero maggiore di rischi rispetto alla media delle auto circolanti nel nostro Paese &#8211; le parole di Arban riportate da &#8216;Repubblica&#8217; &#8211; tra cui incidenti o <strong>danni<\/strong> pregressi&#8221;.<\/p>\n<p>I numeri sono utili ad avere un quadro preciso della situazione, aiutando i potenziali acquirenti a orientarsi al momento dell&#8217;acquisto. Se \u00e8 vero che statisticamente le Fortwo risultano pi\u00f9 inclini a presentare dei fattori di rischio, \u00e8 altrettanto vero che prima di comprarle, gli acquirenti possono fare tutte le <strong>verifiche<\/strong> del caso.<\/p>\n<p>Sul portale Carfax, per esempio, inserendo il numero di <strong>targa<\/strong> dell&#8217;auto desiderata, si ha accesso a un ampio report relativo alla storia del veicolo come il numero di proprietari precedenti ed eventuali coinvolgimenti in incidenti stradali. Si pu\u00f2 sapere, inoltre, se il contachilometri \u00e8 stato alterato, se l&#8217;auto proviene dall&#8217;estero e se ha subito dei danni.<\/p>\n","protected":false},"excerpt":{"rendered":"Smart Fortwo, attenzione alle &#8220;truffe&#8221; sul mercato dell&#8217;usato: ecco che cosa bisogna controllare bene prima di acquistarne una di seconda mano","protected":false},"author":158396758,"featured_media":227011,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[25915],"tags":[420890848],"coauthors":[420891339],"class_list":{"0":"post-227009","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-notizie","8":"tag-auto-usate","9":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2024\/06\/Smart-Fortwo.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/227009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/158396758"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=227009"}],"version-history":[{"count":4,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/227009\/revisions"}],"predecessor-version":[{"id":232702,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/227009\/revisions\/232702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/227011"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=227009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=227009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=227009"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=227009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}