{"id":234167,"date":"2024-07-03T09:12:40","date_gmt":"2024-07-03T07:12:40","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=234167"},"modified":"2024-10-16T10:52:53","modified_gmt":"2024-10-16T08:52:53","slug":"immatricolazioni-auto-alimentazione","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/auto\/immatricolazioni-auto-alimentazione\/234167\/","title":{"rendered":"Immatricolazioni auto in calo, i modelli pi\u00f9 venduti per alimentazione"},"content":{"rendered":"<p>Rispetto al 2019, il <strong>mercato dell&#8217;auto<\/strong> in Italia non riesce a risollevarsi. Il primo semestre del 2024 ha fatto registrare una timida crescita del 5,3% in confronto allo scorso anno, grazie a 886.386 immatricolazioni contro le 841.573 precedenti, ma se operiamo un parallelo con l&#8217;ultimo anno antecedente alla pandemia, il risultato \u00e8 molto negativo: <strong>-18,3%.<\/strong> Nel precedente mese di giugno sono state immatricolate in Italia 160.046 auto, a fronte delle 139.150 del 2023, pari ad un aumento del +15%. In questo caso il risultato si appoggia molto agli <a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/italiani-cambiano-meno-auto\/233415\/\">incentivi statali,<\/a> finiti bruscamente in pochissimo tempo per le auto elettriche.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/immatricolazioni-auto-alimentazione\/234167\/#Le_immatricolazioni_per_alimentazione_a_giugno\" title=\"Le immatricolazioni per alimentazione a giugno\">Le immatricolazioni per alimentazione a giugno<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/immatricolazioni-auto-alimentazione\/234167\/#Le_piu_vendute_fra_benzina_e_diesel\" title=\"Le pi\u00f9 vendute fra benzina e diesel\">Le pi\u00f9 vendute fra benzina e diesel<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/immatricolazioni-auto-alimentazione\/234167\/#Le_ibride_ed_elettriche_piu_vendute\" title=\"Le ibride ed elettriche pi\u00f9 vendute\">Le ibride ed elettriche pi\u00f9 vendute<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Le_immatricolazioni_per_alimentazione_a_giugno\">Le immatricolazioni per alimentazione a giugno<\/span><\/h2>\n<p>Osservando le performance delle alimentazioni in giugno, il motore a <strong>benzina<\/strong>, seppur in crescita in volume, cala di 1,9 punti e si arresta al 26,5% di quota, 30,2% nel cumulato (+2,4 p.p.). Il <strong>diesel\u00a0<\/strong>cede oltre un quinto dei volumi e scende di 5,7 punti al 12,8% di quota nel mese e al 14,6% nel 1\u00b0 semestre (-4,8 p.p.). Notevole la <strong>crescita del GPL <\/strong>che sale in giugno al 10,1% del totale (+1,7 p.p.) e al 9,1% in gennaio-giugno (+0,2 p.p.), il metano con 77 unit\u00e0 non raggiunge neppure lo 0,1% del mercato nel mese, mentre mantiene tale quota nel cumulato.<\/p>\n<p>Le vetture ibride assorbono il 38,7% di share e il 38,9% nei 6 mesi (rispettivamente +3,9 p.p. e +3,6 p.p.), con un 11,1% per le \u201c<em>full<\/em>\u201d hybrid e 27,6% per le \u201c<em>mild<\/em>\u201d hybrid in giugno. La crescita pi\u00f9 sostanziosa \u00e8 quella delle<strong> auto BEV<\/strong>, grazie agli incentivi e alle vetture in pronta consegna, salgono all\u20198,3% di share (+3,9 p.p. e al 3,9% in gennaio-giugno), mentre le Plug-in retrocedono di 1,9 punti rispetto a un anno fa, al 3,5% (3,3% nel semestre).<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Le_piu_vendute_fra_benzina_e_diesel\">Le pi\u00f9 vendute fra benzina e diesel<\/span><\/h2>\n<p>Fra le auto a benzina pi\u00f9 vendute di giugno troviamo una vecchia conoscenza, la <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/citroen\/citroen-c3\/\">Citroen C3<\/a><\/strong> che continua a registrare numeri impressionanti, in attesa che la nuova generazione entri a pieno regime. La francese ha messo in fila 3.643 immatricolazioni, seguita dalla <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/mg\/mg-zs\/\">MG ZS<\/a><\/strong> con 2.628 unit\u00e0 e dalla <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/opel\/opel-corsa\/\">Opel Corsa<\/a><\/strong> che si ferma a 2.450. Fra le vetture a gasolio la palma della migliore va ad appannaggio della <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/volkswagen\/volkswagen-tiguan\/\">Volkswagen Tiguan<\/a><\/strong>, un C-SUV particolarmente apprezzato per la sua versatilit\u00e0 e capacit\u00e0 di affrontare pi\u00f9 scenari, grazie a 1.732 immatricolazioni. Sul podio salgono anche <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/audi\/audi-q3\/\">Audi Q3<\/a><\/strong> (1.355 unit\u00e0 immatricolate) e <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/peugeot\/peugeot-3008\/\">Peugeot 3008<\/a><\/strong> (1.060).<\/p>\n<p>Segnaliamo anche il buon andamento delle vetture a GPL, con <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/dacia\/dacia-sandero\/\">Dacia Sandero<\/a><\/strong> (6.148),<strong> <a href=\"https:\/\/www.virgilio.it\/motori\/listino\/renault\/renault-captur\/\">Renault Captur<\/a><\/strong> (2.032) e <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/renault\/renault-clio\/\">Renault Clio<\/a><\/strong> (1.844) nei primi tre posti della graduatoria, mentre quelle a metano sono sostanzialmente scomparse con la <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/volkswagen\/volkswagen-polo\/\">Volkswagen Polo<\/a><\/strong> prima con appena 55 unit\u00e0.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Le_ibride_ed_elettriche_piu_vendute\">Le ibride ed elettriche pi\u00f9 vendute<\/span><\/h2>\n<p>Partiamo dalle <strong>mild<\/strong> e <strong>full hybrid<\/strong>, che sono le pi\u00f9 diffuse in assoluto, e fra le quali spicca la regina del nostro mercato: la <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/fiat\/fiat-panda\/\">Fiat Panda<\/a><\/strong>, capace di raggranellare ben <strong>10.576 unit\u00e0<\/strong>. Segue a debita distanza un&#8217;altra icona come la <a href=\"https:\/\/www.virgilio.it\/motori\/curiosita\/spot-fiat-500-senza-logo\/230352\/\">Fiat 500<\/a> che stavolta non va oltre le 3.677 immatricolazioni, mentre la medaglia di bronzo \u00e8 tutta della <a href=\"https:\/\/www.virgilio.it\/motori\/auto\/fotonotizia\/toyota-yaris-cross-2024-prezzi-allestimenti\/212035\/\">Toyota Yaris Cross<\/a> con 3.322 unit\u00e0. Fra le plug-in al primo posto troviamo <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/cupra\/cupra-formentor\/\">Cupra Formentor<\/a><\/strong> forte delle sue 904 immatricolazioni, scortata dalla <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/ford\/ford-kuga\/\">Ford Kuga<\/a><\/strong> (427) e<strong> <a href=\"https:\/\/www.virgilio.it\/motori\/listino\/bmw\/bmw-x1\/\">BMW X1<\/a><\/strong> (285).<\/p>\n<p>Fra le elettriche che corrono anche grazie all&#8217;apporto degli incentivi, spiccano indubbiamente le auto a marchio Tesla, vero punto di riferimento del settore: <strong>Model 3<\/strong> (3.282) e <strong>Model Y<\/strong> (1.699) sono le pi\u00f9 vendute. Sul terzo gradino del podio c&#8217;\u00e8 spazio per la <strong><a href=\"https:\/\/www.virgilio.it\/motori\/listino\/dacia\/dacia-spring\/\">Dacia Spring<\/a><\/strong> (878), la citycar alla spina ideale per destreggiarsi nel traffico senza affanno.<\/p>\n","protected":false},"excerpt":{"rendered":"Il mercato dell&#8217;auto in Italia registra un calo nel primo semestre del 2024, rispetto allo stesso periodo del 2019, l&#8217;ultimo prima della Pandemia","protected":false},"author":183220833,"featured_media":234168,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420889857],"tags":[],"coauthors":[420891333,420891331],"class_list":{"0":"post-234167","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-auto","8":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2024\/07\/Immatricolazioni-auto-2024.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/234167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220833"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=234167"}],"version-history":[{"count":5,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/234167\/revisions"}],"predecessor-version":[{"id":246975,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/234167\/revisions\/246975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/234168"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=234167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=234167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=234167"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=234167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}