{"id":271747,"date":"2025-03-18T14:00:58","date_gmt":"2025-03-18T13:00:58","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=271747"},"modified":"2025-03-18T16:49:25","modified_gmt":"2025-03-18T15:49:25","slug":"transizione-green-dichiarazioni-urso","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/auto\/transizione-green-dichiarazioni-urso\/271747\/","title":{"rendered":"Transizione green, l&#8217;Italia dovrebbe trainare l&#8217;Europa intera: la &#8220;ricetta Urso&#8221;"},"content":{"rendered":"<p>Il <strong>Governo italiano<\/strong> sta adottando una strategia decisa per affrontare le sfide del settore automotive, con un focus primario sul sostegno alle imprese e la tutela dei lavoratori. In occasione del <strong>Tavolo Automotive<\/strong>, il ministro delle Imprese Adolfo Urso ha delineato le priorit\u00e0 dell\u2019Esecutivo, evidenziando un cambio di rotta rispetto al passato. \u201c<em>Siamo un Governo responsabile: il nostro obiettivo \u00e8 mettere in sicurezza le imprese e tutelare i lavoratori. Per questo, incentiviamo le aziende della filiera automotive a diversificare e riconvertire le proprie attivit\u00e0 verso settori ad alto potenziale di crescita, come difesa, aerospazio, blue economy e cybersicurezza<\/em>\u201d, cos\u00ec ha parlato Urso.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/transizione-green-dichiarazioni-urso\/271747\/#Niente_piu_Ecobonus\" title=\"Niente pi\u00f9 Ecobonus\">Niente pi\u00f9 Ecobonus<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/transizione-green-dichiarazioni-urso\/271747\/#Riconversione_del_settore_e_sostegno_allacquisto_di_auto_ecologiche\" title=\"Riconversione del settore e sostegno all\u2019acquisto di auto ecologiche\">Riconversione del settore e sostegno all\u2019acquisto di auto ecologiche<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/transizione-green-dichiarazioni-urso\/271747\/#Il_tema_Stellantis\" title=\"Il tema Stellantis\">Il tema Stellantis<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Niente_piu_Ecobonus\">Niente pi\u00f9 Ecobonus<\/span><\/h2>\n<p>Abbandono dell&#8217;Ecobonus Italia per i consumatori: una delle decisioni pi\u00f9 significative \u00e8 la conferma dell&#8217;<strong>addio agli incentivi diretti<\/strong> ai consumatori per l&#8217;acquisto di auto a basse emissioni. Questa scelta \u00e8 motivata dalla volont\u00e0 di concentrare le risorse sul sostegno alla componentistica, un comparto particolarmente colpito dalla crisi produttiva delle Case automobilistiche tedesche. L&#8217;obiettivo principale \u00e8 supportare l&#8217;intera filiera automotive italiana, allocando <strong>2,5 miliardi di euro<\/strong> per il triennio 2025-27. Gi\u00e0 per quest&#8217;anno, sono previsti 1,6 miliardi di euro destinati ad accordi per l&#8217;innovazione, contratti di sviluppo e credito d&#8217;imposta. Ulteriori 100 milioni di euro saranno indirizzati a interventi mirati sulla domanda, non specificamente per l&#8217;acquisto di vetture, ma definiti in accordo con la filiera.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Riconversione_del_settore_e_sostegno_allacquisto_di_auto_ecologiche\">Riconversione del settore e sostegno all\u2019acquisto di auto ecologiche<\/span><\/h2>\n<p>Parallelamente, il governo sta attivamente promuovendo la diversificazione e la riconversione delle attivit\u00e0 delle aziende del settore automotive verso settori ad alto potenziale di crescita come la <strong>difesa<\/strong>, l&#8217;aerospazio, la blue economy e la <strong>cybersicurezza<\/strong>. Il ministro Urso ha sottolineato come questi comparti in forte espansione e ad alta redditivit\u00e0 possano salvaguardare e valorizzare le competenze dei lavoratori del settore auto, sfruttando le loro capacit\u00e0 tecniche e il capitale umano gi\u00e0 formato.<\/p>\n<p>Sul fronte europeo, l&#8217;Italia si \u00e8 fatta promotrice di un piano bonus alla domanda realizzato a livello continentale. L&#8217;obiettivo \u00e8 incentivare in modo omogeneo e costante l&#8217;acquisto di <strong>veicoli ecologicamente sostenibili<\/strong>, senza necessariamente limitarsi all&#8217;elettrico. Questa proposta sta guadagnando consensi a Bruxelles. Inoltre, grazie a un non-paper sul settore auto, l&#8217;Italia ha indotto la Commissione Europea a includere nel Piano d&#8217;Azione due condizioni ritenute necessarie: il rinvio delle sanzioni e l&#8217;anticipo alla seconda met\u00e0 di quest&#8217;anno della revisione del regolamento sui veicoli leggeri, inizialmente prevista per fine 2026.<\/p>\n<p>L&#8217;Italia punta con decisione alla neutralit\u00e0 tecnologica, con un focus particolare sui <a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/decreto-biocarburanti-protesta-federmetano\/265409\/\">biocarburanti<\/a> e l&#8217;idrogeno, nonch\u00e9 alla revisione del metodo di calcolo delle emissioni e allo stanziamento di risorse per l&#8217;autonomia strategica sulle batterie elettriche.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Il_tema_Stellantis\">Il tema Stellantis<\/span><\/h2>\n<p>Infine, durante il Tavolo Automotive si \u00e8 discusso del Piano Italia presentato da <a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/stellantis-partner-olimpiadi-milano-cortina-2026\/270779\/\">Stellantis<\/a> lo scorso dicembre. Il ministro ha espresso apprezzamento per l&#8217;anticipo dell&#8217;avvio della produzione della <a href=\"https:\/\/www.virgilio.it\/motori\/auto\/auto-ibride\/fiat-500-ibrida-mirafiori-primo-esemplare\/269115\/\">Fiat 500 ibrida<\/a> a Mirafiori. \u00c8 prevista la convocazione di un ulteriore tavolo per affrontare la situazione di Termoli, alla luce della sospensione del progetto della Gigafactory. La strategia dell\u2019Esecutivo italiano per il settore automotive si concentra sul rafforzamento della filiera attraverso investimenti mirati, sperando che il grande Gruppo con a capo John Elkann non dimentichi le realt\u00e0 che sono collocate nel Belpaese.<\/p>\n","protected":false},"excerpt":{"rendered":"L&#8217;Italia si muove a grandi passi verso la transizione green, ma insegue una strada ben precisa, richiedendo incentivi europei e non nazionali","protected":false},"author":183220833,"featured_media":271750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420889857],"tags":[],"coauthors":[420891333,420891331],"class_list":{"0":"post-271747","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-auto","8":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2025\/03\/urso-transizione-green.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/271747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220833"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=271747"}],"version-history":[{"count":5,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/271747\/revisions"}],"predecessor-version":[{"id":305844,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/271747\/revisions\/305844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/271750"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=271747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=271747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=271747"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=271747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}