{"id":277241,"date":"2025-05-02T19:45:55","date_gmt":"2025-05-02T17:45:55","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=277241"},"modified":"2025-05-02T20:19:04","modified_gmt":"2025-05-02T18:19:04","slug":"gp-miami-prove-libere-venerdi-2025","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/motor-sport\/formula-1\/gp-miami-prove-libere-venerdi-2025\/277241\/","title":{"rendered":"Ferrari corregge il setup e stabilizza la SF-25: analisi Fp1 GP Miami"},"content":{"rendered":"<p class=\"\" data-start=\"87\" data-end=\"509\">Sessanta minuti per capire la vettura e sistemarla al meglio. La sola ora a disposizione delle FP1 rende il compito piuttosto arduo, tenendo presente che nella prossima sessione si inizia subito a fare sul serio con la prima delle due qualifiche, quella valevole per comporre la griglia di partenza della Sprint Race. Ecco perch\u00e9 il lavoro fatto da casa con il simulatore assume un aspetto fondamentale nel fine settimana.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/formula-1\/gp-miami-prove-libere-venerdi-2025\/277241\/#Ferrari_soffre_nelle_curve_lente_con_le_Medium\" title=\"Ferrari soffre nelle curve lente con le Medium\">Ferrari soffre nelle curve lente con le Medium<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/formula-1\/gp-miami-prove-libere-venerdi-2025\/277241\/#Ritocco_al_setup\" title=\"Ritocco al setup\">Ritocco al setup<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/formula-1\/gp-miami-prove-libere-venerdi-2025\/277241\/#Passo_gara_e_test_sulle_Soft\" title=\"Passo gara e test sulle Soft\">Passo gara e test sulle Soft<\/a><ul><li><a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/formula-1\/gp-miami-prove-libere-venerdi-2025\/277241\/#GP_Miami_2025_Classifica_finale_prove_libere\" title=\"GP Miami 2025: Classifica finale prove libere\u00a0\">GP Miami 2025: Classifica finale prove libere\u00a0<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ferrari_soffre_nelle_curve_lente_con_le_Medium\">Ferrari soffre nelle curve lente con le Medium<\/span><\/h2>\n<p>Le due Rosse abbandonano la pit lane senza perdere tempo. Lo fanno ambedue con le Pirelli a banda gialla. Si cura in maniera particolare l&#8217;attivazione delle gomme. Il primo giro \u00e8 piuttosto blando, considerando che la pista \u00e8 molto sporca, e il grip a disposizione \u00e8 poco. Si \u00e8 scelta la <a href=\"https:\/\/www.virgilio.it\/motori\/glossario\/mescola\/\">mescola<\/a> Medium per dare continuit\u00e0 e testare l&#8217;assetto dell&#8217;auto al meglio delle possibilit\u00e0. Charles effettua un passaggio pulito, mentre Lewis spende qualche correzione nel T2.<\/p>\n<p>Nel secondo intento, decisamente pi\u00f9 spinto, in curva 11 <strong>perde l&#8217;avantreno<\/strong> in entrata ed \u00e8 costretto a controllare l&#8217;auto per un eccesso di rotazione. Mentre alla 17 manca il punto di corda. In generale commenta sensazioni nei tratti lenti non ottimali. Non un buon segnale, ma va detto che l&#8217;aderenza \u00e8 poca. Lewis pi\u00f9 pulito risulta un pelo pi\u00f9 rapido del compagno.<\/p>\n<p>Nel passaggio successivo <a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/formula-1\/charles-leclerc-eta-profilo\/270445\/\">Leclerc<\/a> \u00a0trova un guida migliore. Specie alla 17, si nota un anteriore molto pi\u00f9 solido rispetto al tentativo precedente. Anche l&#8217;inglese pare pi\u00f9 a su agio con la vettura, sebbene si noti come in staccata faccia sempre pi\u00f9 fatica ad incidere osservando i suoi on board. Va detto che ambedue i ferraristi agiscono sul manettino del brake shaping per massimizzare le staccate.<\/p>\n<p>Si procede con altri due giri spinti, intervallati da altrettanti cool down lap che portano poi al termine di questo primo run. Possiamo dire che il bilanciamento della Rossa non \u00e8 male, sebbene si notano alcuni limiti soliti, come la carenza di rotazione che rende faticoso prendere l&#8217;apice di alcune curve. Nei cambi di direzione del T1 il rendimento pare abbastanza buono, dove retrotreno e avantreno sono <strong>abbastanza stabili<\/strong>.<\/p>\n<p>Arrivano maggiori difficolt\u00e0 nei tratti pi\u00f9 guidati, dove alle basse velocit\u00e0 i due alfieri della rossa sono costretti a remare un po&#8217; con il volante per inserire al meglio la vettura. Specialmente con Leclerc, si notano quei piccoli colpetti classici sul volante per correggere la traiettoria in inserimento, segnale che l&#8217;aderenza meccanica non \u00e8 ottimale come dovrebbe.<\/p>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ritocco_al_setup\">Ritocco al setup<\/span><\/h2>\n<p>Per ottimizzare il rendimento della vettura, nella pausa ai box il team di Maranello decide di <strong>modificare l&#8217;assetto<\/strong> di entrambe le auto italiane. Si interviene pertanto sulle altezze da terra per potenziare il lavoro dei <a href=\"https:\/\/www.virgilio.it\/motori\/glossario\/canali-venturi\/\">Canali Venturi<\/a> sulla rigidezza di entrambi gli assi. La ragione \u00e8 semplice: ottenere maggiore performance. Charles \u00e8 gi\u00e0 in pista, avendo realizzato un passaggio in meno nel run precedente. L&#8217;outlap \u00e8 piuttosto blando, per poi lanciarsi nel primo tentativo push.<\/p>\n<p>E in effetti, osservando la guidabilit\u00e0 della numero 16, si nota un avantreno pi\u00f9 solido nei tratti pi\u00f9 lenti, con maggiore facilit\u00e0 nel salire sul cordolo, come sull&#8217;ultima curva. Gli interventi sulla rigidezza <strong>sembrano funzionare<\/strong>, senza perdere stabilit\u00e0 nei cambi di direzione. Va detto che nel T1 deve ancora arrivare un passo avanti per ottimizzare la prestazione, dove le gomme non sembrano mai attivate nel modo corretto.<\/p>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Passo_gara_e_test_sulle_Soft\">Passo gara e test sulle Soft<\/span><\/h2>\n<p>Nell&#8217;ultima parte delle prove libere si testa il rendimento dell&#8217;auto con alto quantitativo di carburante a bordo. Per la simulazione passo gara si utilizzano sempre le Pirelli cerchiate di giallo su entrambe le monoposto. Questo significa che i giri push, dopo il ritocco al setup, sono stati effettuati con una vettura pi\u00f9 pesante. Il comportamento della SF-25 pare piuttosto <strong>puntato sull\u2019anteriore<\/strong>, con una certa tendenza al sovrasterzo a centro curva.<\/p>\n<p>Il posteriore non \u00e8 stabilissimo e ogni tanto sembra un po\u2019 ballerino, sebbene resti abbastanza sotto controllo. Tra i due ferraristi, chi soffre maggiormente \u00e8 sempre Hamilton, in difficolt\u00e0 rispetto al compagno di squadra. Difficile dare una stima sul passo, anche perch\u00e9 il test non \u00e8 stato molto approfondito. Dopo un\u2019ulteriore sosta ai box, si passa alle Soft per provare il giro push con la massima aderenza.<\/p>\n<p><a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/formula-1\/lewis-hamilton-eta-profilo\/270337\/\">Hamilton<\/a> lamenta ancora sottosterzo, una carenza di rotazione che non riesce a gestire come Leclerc. Per Charles le cose vanno un po\u2019 meglio, sebbene nel suo unico tentativo non sia riuscito a <strong>massimizzare il rendimento<\/strong>. Peccato per la bandiera rossa causata da Bearman, che stoppa la sessione e di fatto decreta il termine delle Fp1. Per finire: <a href=\"https:\/\/www.virgilio.it\/motori\/motor-sport\/formula-1\/gp-miami-ferrari-preview-2025\/277095\/\">Ferrari<\/a> ha dovuto aggiustare il tiro sulla messa a punto, perch\u00e9 il balance iniziale non era ottimale.<\/p>\n<p>Tenendo conto dell\u2019ultimo giro di Charles, rispetto a Piastri c\u2019\u00e8 ancora margine di miglioramento in tre punti chiave: curva 7, 11 e 12. Si tratta, nello specifico, della velocit\u00e0 di percorrenza nel curvone ad ampio raggio del T1 e della fase di ingresso dove ha inizio la zona pi\u00f9 guidata. Nessun feedback particolare da parte del monegasco, che nel giro di rientro verso il garage non appare super soddisfatto, ma nemmeno deluso dai cambiamenti apportati.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"GP_Miami_2025_Classifica_finale_prove_libere\"><span id=\"GP_Arabia_Saudita_Classifica_finale_prove_libere_3\" class=\"ez-toc-section\">GP Miami 2025: Classifica finale prove libere\u00a0<\/span><\/span><\/h3>\n<ul class=\"wp-block-list\">\n<li><strong>Oscar<\/strong> <strong>Piastri<\/strong> (McLaren) <strong>1:27.128s<\/strong><\/li>\n<li><strong>Charles<\/strong>\u00a0<strong>Leclerc<\/strong> (Ferrari) +0.356s<\/li>\n<li><strong>Max<\/strong> <strong>Verstappen<\/strong> (Red Bull) +0.430s<\/li>\n<li><strong>Carlos<\/strong>\u00a0<strong>Sainz<\/strong> (Williams) +0.550s<\/li>\n<li><strong>Alexander<\/strong> <strong>Albon<\/strong> (Williams) +0.827s<\/li>\n<li><strong><span class=\"max-desktop:hidden\">Isack<\/span><\/strong>\u00a0<strong><span class=\"max-tablet:hidden\">Hadjar <\/span><\/strong><span class=\"max-tablet:hidden\">(Racing Bulls) +0.840s<\/span><\/li>\n<li><strong>George<\/strong>\u00a0<strong>Russell<\/strong> (Mercedes) +0.930s<\/li>\n<li><strong>Yuki<\/strong> <strong>Tsunoda<\/strong> (Red Bull) +1.027s<\/li>\n<li><strong>Andrea<\/strong> <strong>Kimi<\/strong> <strong>Antonelli<\/strong> (Mercedes) +1.099s<\/li>\n<li><strong>Fernando<\/strong> <strong>Alosno<\/strong> (Aston Martin) +1.115s<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"Modifiche all&#8217;assetto della SF-25 per trovare il bilanciamento corretto: Ferrari sistema la Rossa nelle FP1","protected":false},"author":183220864,"featured_media":277261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420891467],"tags":[420890863,420891477],"coauthors":[420891361,420891360],"class_list":{"0":"post-277241","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-formula-1","8":"tag-ferrari","9":"tag-gp-miami","10":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2025\/05\/Charles-Leclerc-Fp1-Miami.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/277241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220864"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=277241"}],"version-history":[{"count":6,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/277241\/revisions"}],"predecessor-version":[{"id":277265,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/277241\/revisions\/277265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/277261"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=277241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=277241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=277241"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=277241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}