{"id":284563,"date":"2025-06-28T17:20:59","date_gmt":"2025-06-28T15:20:59","guid":{"rendered":"https:\/\/www.virgilio.it\/motori\/?p=284563"},"modified":"2025-06-29T08:50:43","modified_gmt":"2025-06-29T06:50:43","slug":"auto-usate-frodi-europa-2024","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/notizie\/auto-usate-frodi-europa-2024\/284563\/","title":{"rendered":"Auto usate, frodi per oltre 5 miliardi di euro l&#8217;anno"},"content":{"rendered":"<p>Nel 2024 il mercato europeo delle <strong>auto usate<\/strong> ha toccato quota 635 miliardi di euro. Peccato che secondo carVertical quasi il 5% dei mezzi di seconda mano nel Vecchio Continente gira con un contachilometri truccato. E quattro veicoli su dieci hanno danni pregressi mai dichiarati. <em>\u201cLe perdite stimate? Oltre 5,3 miliardi di euro all\u2019anno\u201d<\/em>. avverte carVertical. Spulciando studi precedenti del Parlamento Europeo, la cifra schizza fino a 8,77 miliardi.<\/p>\n<p><!--more--><\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/auto-usate-frodi-europa-2024\/284563\/#Un_rischio_per_la_sicurezza\" title=\"Un rischio per la sicurezza\">Un rischio per la sicurezza<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/auto-usate-frodi-europa-2024\/284563\/#Le_soluzioni_degli_altri_Paese\" title=\"Le soluzioni degli altri Paese\">Le soluzioni degli altri Paese<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Un_rischio_per_la_sicurezza\">Un rischio per la sicurezza<\/span><\/h2>\n<p>Non \u00e8 solo una questione di portafoglio. Quando compri un\u2019auto e scopri che i <strong>chilometri<\/strong> segnati non corrispondono, rischi pure di trovarti un&#8217;arma pericolosa tra le mani. E la <strong>sicurezza<\/strong>, in strada, va presa sul serio. La criticit\u00e0 \u00e8 la giungla dei dati. Le informazioni per smascherare queste operazioni ci sarebbero pure. Ma tra norme sulla privacy, registri cartacei e banche dati arretrate, i furbetti finiscono per farla franca.<\/p>\n<p><em>\u201cSuggeriamo di trovare il miglior equilibrio possibile tra la tutela dei dati personali e la necessit\u00e0 di offrire strumenti efficaci alle imprese che operano nel settore digitale\u201d<\/em>, spiega Rokas Medonis, CEO di carVertical. <em>\u201cQuando un\u2019auto cambia proprietario, le informazioni che la riguardano dovrebbero poter &#8216;seguire&#8217; il veicolo, in modo che i consumatori restino informati. Non si tratta di rinunciare alla privacy, ma di garantire un accesso responsabile ai dati, evitando frammentazioni che finiscono per favorire pratiche scorrette&#8221;<\/em>.<\/p>\n<p>Una regola chiara favorirebbe un gioco pulito. Perch\u00e9, come ricorda ancora Medonis,<em> \u201cI Paesi non sempre si <strong>scambiano i dati<\/strong> dei veicoli, molti registri di <a href=\"https:\/\/www.virgilio.it\/motori\/notizie\/auto-usate-spunta-la-truffa-del-contachilometri-fermo\/273326\/\">chilometraggio<\/a> o dei danni non sono digitalizzati e manca un approccio equilibrato alla tracciabilit\u00e0 delle vendite. Questo rende le frodi facili da occultare, danneggiando i consumatori e penalizzando le imprese oneste, mentre chi agisce in modo scorretto riesce a restare nell\u2019ombra&#8221;<\/em>.<\/p>\n<p>Prendi la <strong>Germania<\/strong>: esporta quasi 2 milioni di auto usate l\u2019anno. Ma spesso i dati viaggiano a met\u00e0. Succede lo stesso in Belgio e Paesi Bassi: sistemi come Car-Pass, Nationale Auto Pas o l\u2019autorit\u00e0 RDW funzionano bene nei confini locali, poi, per\u00f2, quando la macchina varca il confine le informazioni si fermano. E l\u2019<a href=\"https:\/\/www.virgilio.it\/motori\/auto\/usate-italia-dati-aprile-2025\/284427\/\">Italia<\/a>? Anche peggio: i dati sui danni non si condividono regolarmente. E dunque gli acquirenti di una vettura importata incorrono nei problemi di trasparenza di altri. A rimetterci sono soprattutto i Paesi dell\u2019<strong>Est Europa<\/strong>, importatori di numerosi veicoli da Germania, Belgio e Olanda.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Le_soluzioni_degli_altri_Paese\">Le soluzioni degli altri Paese<\/span><\/h2>\n<p>Eppure, una soluzione esiste. <strong>Svezia e Finlandia<\/strong>, ad esempio, hanno dimostrato la possibilit\u00e0 di <strong>proteggere la privacy<\/strong> senza nascondere i problemi. Da loro, chiunque compri un veicolo pu\u00f2 vedere subito chilometri, <a href=\"https:\/\/www.virgilio.it\/motori\/info-utili\/tagliando-auto-quando-farlo-cosa-prevede-costi\/154723\/\">tagliandi<\/a>, proprietari precedenti. A sua volta, il Regno Unito, fuori dall\u2019Ue, d\u00e0 lezioni: l\u2019accesso ai dati \u00e8 immediato. \u00c8 questione di mettere la tecnologia gi\u00e0 presente a sistema. Se l\u2019Unione Europea vuole un mercato unico vero, \u00e8 necessario un cambio di registro. Un quadro normativo unico, digitale, trasparente, che non lasci spazio a trucchetti da meccanico improvvisato.<\/p>\n<p>E la domanda finale la lascia Medonis: <em>\u201cNorme pi\u00f9 chiare e una condivisione equilibrata dei dati possono rafforzare la fiducia nel mercato, proteggere i consumatori e sostenere le imprese oneste. La domanda che dobbiamo porci \u00e8: vogliamo proteggere informazioni che non mettono a rischio la privacy, ma che possono prevenire frodi, o continuare a tollerare una mancanza di trasparenza che danneggia tutti?\u201d<\/em>. La palla, stavolta, \u00e8 tutta a Bruxelles.<\/p>\n","protected":false},"excerpt":{"rendered":"Frodi auto usate: 5 miliardi di danni l\u2019anno tra chilometri falsi e info mancanti. Serve un sistema unico europeo digitale, basato sulla trasparenza","protected":false},"author":183220841,"featured_media":284569,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[25915],"tags":[420890848],"coauthors":[420891349,420891347],"class_list":{"0":"post-284563","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-notizie","8":"tag-auto-usate","9":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2025\/06\/Truffe-auto-usate-2024.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/284563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220841"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=284563"}],"version-history":[{"count":5,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/284563\/revisions"}],"predecessor-version":[{"id":284618,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/284563\/revisions\/284618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/284569"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=284563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=284563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=284563"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=284563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}