{"id":73941,"date":"2019-02-06T10:05:20","date_gmt":"2019-02-06T09:05:20","guid":{"rendered":"http:\/\/motorlife.it\/?p=73941"},"modified":"2024-07-30T10:50:02","modified_gmt":"2024-07-30T08:50:02","slug":"cosa-sono-le-cafe-racer","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/moto\/cosa-sono-le-cafe-racer\/73941\/","title":{"rendered":"Caf\u00e8 Racer, l&#8217;evasione perfetta per un&#8217;anima ribelle"},"content":{"rendered":"<p>Nel panorama delle due ruote, poche moto riescono a emanare fascino come le <strong>Caf\u00e8 Racer<\/strong>. Nati da una cultura ribelle e appassionata, questi esemplari costituiscono la fusione perfetta tra stile e velocit\u00e0, lascito di un percorso che affonda le radici nella Gran Bretagna del dopoguerra. In uno dei periodi pi\u00f9 bui della storia, c\u2019era voglia di evadere dalla realt\u00e0, fatta di macerie e brutti ricordi. Perch\u00e9 allora non crearsene di nuovi e migliori? Da qui \u00e8 nata una storia magnifica, capace di cambiare in maniera definitiva la storia su strada.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/moto\/cosa-sono-le-cafe-racer\/73941\/#Da_moto_di_serie_a_bolidi_improvvisati\" title=\"Da moto di serie a bolidi improvvisati\">Da moto di serie a bolidi improvvisati<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/moto\/cosa-sono-le-cafe-racer\/73941\/#I_modelli_che_ne_ereditano_lidentita\" title=\"I modelli che ne ereditano l&#8217;identit\u00e0\">I modelli che ne ereditano l&#8217;identit\u00e0<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Da_moto_di_serie_a_bolidi_improvvisati\">Da moto di serie a bolidi improvvisati<\/span><\/h2>\n<p>Correvano gli <strong>anni Cinquanta<\/strong> quando, tra i pub londinesi, si instill\u00f2 tra i giovani una passione: trasformare le motociclette di serie in bolidi da corsa improvvisati. Vennero allora alla luce le Caf\u00e8 Racer, il cui nome derivava dalle sfide clandestine disputate tra un caf\u00e8 e l\u2019altro. I veicoli andavano oltre alle performance. Che, certo, costituivano una parte importante, ma giustificavano giusto una parte del fascino emanato.<\/p>\n<p>Le <strong>modifiche \u201cfai da te\u201d<\/strong> erano all\u2019ordine del giorno: il serbatoio allungato e filante traeva spunto dalle belve da motorsport dell\u2019epoca, mentre il manubrio diventava basso e \u201cclip-on\u201d per una posizione di guida aggressiva. La sella monoposto accentuava l\u2019impronta sportiva, le pedane arretrate assicuravano controllo in curva e un\u2019esperienza a bordo di classe superiore. I <strong>silenziatori a megatrono<\/strong> emettevano, invece, un sound cupo e coinvolgente.<\/p>\n<p>A completare il look, <strong>colori vivaci e grafiche accattivanti<\/strong>, adatte a brillare nello stile: qualcosa di differente, rispetto alle solite produzioni che dettavano allora banco. Per le anime anticonformiste fu, dunque, amore a prima vista. Stufi degli schemi tradizionali, piacevoli s\u00ec ma abbastanza ripetitivi, videro nelle Caf\u00e8 Racer uno strumento di evasione. Attorno a tale cultura si svilupp\u00f2 un movimento sociale, <strong>fondato su club, raduni ed eventi specifici<\/strong>. Gli \u201cadepti\u201d erano, di norma, dei giovani ribelli, contrari alle convenzioni. Nelle gare e nella personalizzazione dei rispettivi mezzi trovavano una via di esprimersi.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"I_modelli_che_ne_ereditano_lidentita\">I modelli che ne ereditano l&#8217;identit\u00e0<\/span><\/h2>\n<p>Nel corso degli anni le tecniche di progettazione e la qualit\u00e0 dei materiali \u00e8 migliorata in modo sensibile. Oggi risultano pi\u00f9 leggeri, grazie all\u2019impiego di alluminio e della fibra di carbonio, il che le avvicina alle <a href=\"https:\/\/www.virgilio.it\/motori\/auto\/auto-sportive-due-posti\/233906\/\">auto sportive<\/a> odierne. I professionisti curano al massimo i dettagli, con finiture raffinate, grafiche elaborate e componenti di pregevole fattura. Il genere ha lasciato un\u2019eredit\u00e0 indelebile nell\u2019ambito delle due ruote. Le loro peculiarit\u00e0 hanno pure ispirato diverse compagnie a realizzare delle <strong>interpretazioni evolute<\/strong>. Ancora oggi, affascinano nella versatilit\u00e0, adatte sia a uno scenario urbano sia su strada o in pista.<\/p>\n<p>Tra i modelli preferiti dominano le proposte britanniche, tipo la <strong>Brixton Crossfire 125<\/strong>. Alla classica immagine del genere, l\u2019esemplare aggiunge una rotazione ultra-unica, con un sedile sportivo a gradini, un faro a LED circolare, un serbatoio con un design a X idiosincratico. Oltremanica sono altres\u00ec nate la <a href=\"https:\/\/www.virgilio.it\/motori\/moto\/cinque-moto-imperdibili-da-vedere-ad-eicma-2022\/183993\/\">Royal Enfield Continental GT 650<\/a> e la <strong>Triumph Speed Triple 1200 RR<\/strong>. E le italiane? La <strong>MV Agusta Superveloce S<\/strong> \u00e8 considerata dai pi\u00f9 la numero uno tra le carenate. Inoltre, ispirate alle iconiche scrambler monomarcia degli anni Sessanta e Settanta dell\u2019azienda di Borgo Panigale, la Ducati Scrambler Cafe Racer cerca di combinare il meglio dei due mondi.<\/p>\n","protected":false},"excerpt":{"rendered":"Le Caf\u00e8 Racer hanno segnato una rottura coi vecchi paradigmi: i fautori, una comunit\u00e0 di biker restii alle regole, si ribellarono cos\u00ec al sistema","protected":false},"author":183220841,"featured_media":238876,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420889858],"tags":[],"coauthors":[420891347,420891349],"class_list":{"0":"post-73941","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-moto","8":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2019\/02\/Cafe-Racer-cosa-sono.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/73941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220841"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=73941"}],"version-history":[{"count":14,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/73941\/revisions"}],"predecessor-version":[{"id":238991,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/73941\/revisions\/238991"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/238876"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=73941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=73941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=73941"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=73941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}