{"id":77471,"date":"2024-10-22T14:13:23","date_gmt":"2024-10-22T12:13:23","guid":{"rendered":"http:\/\/motorlife.it\/?p=77471"},"modified":"2025-02-03T16:22:35","modified_gmt":"2025-02-03T15:22:35","slug":"morgan-storia-e-curiosita-della-casa-automobilistica","status":"publish","type":"post","link":"https:\/\/www.virgilio.it\/motori\/auto\/morgan-storia-e-curiosita-della-casa-automobilistica\/77471\/","title":{"rendered":"Morgan: storia e curiosit\u00e0 della casa automobilistica senza tempo"},"content":{"rendered":"<p>Un nome simbolo di eleganza e ricercatezza, vetture dotate di uno splendido gusto retr\u00f2 che richiama gli anni \u201930, la casa automobilistica Morgan conosce bene cosa deve avere una bella auto per essere notata. Un brand che ha saputo evolversi con il tempo, superando anche momenti di difficolt\u00e0, e che oggi propone ancora le sue vetture iconiche e tanto ricercate dai collezionisti di ogni et\u00e0.<\/p>\n<p>Le vetture della Morgan sono vetture destinate veramente a pochi appassionati, legati ad un\u2019azienda che hanno saputo diffondere e valorizzare un know-how fondato sulla cura maniacale dei dettagli e votato alla diffusione di uno spirito tipicamente inglese, apprezzato in tutto il mondo.<\/p>\n<div id=\"ez-toc-container\" class=\"counter-hierarchy counter-decimal\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class=\"ez-toc-list\"><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/morgan-storia-e-curiosita-della-casa-automobilistica\/77471\/#Le_origini_della_Morgan_Motor_Company\" title=\"Le origini della Morgan Motor Company\">Le origini della Morgan Motor Company<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/morgan-storia-e-curiosita-della-casa-automobilistica\/77471\/#Levoluzione_e_i_modelli_iconici\" title=\"L&#8217;evoluzione e i modelli iconici\">L&#8217;evoluzione e i modelli iconici<\/a><ul><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/morgan-storia-e-curiosita-della-casa-automobilistica\/77471\/#La_nuova_vita_di_una_marca_iconica\" title=\"La nuova vita di una marca iconica\">La nuova vita di una marca iconica<\/a><\/li><\/ul><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/morgan-storia-e-curiosita-della-casa-automobilistica\/77471\/#Presente_e_futuro_della_Morgan\" title=\"Presente e futuro della Morgan\">Presente e futuro della Morgan<\/a><ul><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/morgan-storia-e-curiosita-della-casa-automobilistica\/77471\/#Morgan_Super_3\" title=\"Morgan Super 3\">Morgan Super 3<\/a><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/morgan-storia-e-curiosita-della-casa-automobilistica\/77471\/#Morgan_Plus_Four_e_Morgan_Plus_Six\" title=\"Morgan Plus Four e Morgan Plus Six\">Morgan Plus Four e Morgan Plus Six<\/a><\/li><\/ul><\/li><li><a href=\"https:\/\/www.virgilio.it\/motori\/auto\/morgan-storia-e-curiosita-della-casa-automobilistica\/77471\/#Qualche_curiosita_sul_marchio_Morgan\" title=\"Qualche curiosit\u00e0 sul marchio Morgan\">Qualche curiosit\u00e0 sul marchio Morgan<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Le_origini_della_Morgan_Motor_Company\"><strong>Le origini della Morgan Motor Company<\/strong><\/span><\/h2>\n<p>La <strong>Morgan Motor Company<\/strong> \u00e8 una <strong>casa automobilistica britannica<\/strong>, fondata nel <strong>1909-1910<\/strong> da Henry Frederick Stanley Morgan a Malvern, nel Worcestershire in Inghilterra, che si caratterizza fin da subito per la sua <strong>produzione artigianale<\/strong> di poche e accurate vetture, dal fascino esclusivamente british e con linee classiche, subito identificabili e senza tempo.<\/p>\n<p>La cura dei dettagli e il lavoro maniacale rendono ogni auto un capolavoro e ogni auto viene realizzata quasi interamente a mano, diventando cos\u00ec protagonista di qualsiasi sfilata di auto, d\u2019epoca o non, grazie anche all\u2019utilizzo, aggiornato nel tempo ma mai sostituito, dei suoi <strong>materiali iconici<\/strong>: alluminio, legno e pelle che la rendono cos\u00ec pregiata e ricercata.<\/p>\n<p>Il <strong>primo modello prodotto<\/strong> \u00e8 un veicolo a tre ruote, la <strong>Three Wheeler<\/strong>, costruito con un telaio tubulare, il motore Jap di derivazione motociclistica (prodotto dall\u2019industria meccanica di John Alfred Prestwich), con un sistema di sospensioni molto innovativo per l\u2019epoca che viene utilizzato ancora oggi. Un veicolo molto particolare e insolito, amato dai collezionisti, la cui <strong>produzione<\/strong> venne <strong>interrotta nel 1952<\/strong> per poi essere <strong>ripresa nel 2011-2012<\/strong>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Levoluzione_e_i_modelli_iconici\">L&#8217;evoluzione e i modelli iconici<\/span><\/h2>\n<p>Dopo il primo modello e in seguito alla crisi del mercato del <strong>1935<\/strong>, l\u2019azienda ha convertito la sua produzione al settore delle <strong>quattro ruote<\/strong>. \u00c8 nata cos\u00ec la <strong>Morgan 4\/4<\/strong>, detta anche <strong>Four Four<\/strong>, che ha decretato il successo dell\u2019azienda e che \u00e8 stata prodotta, con varie rivisitazioni e aggiornamenti, fino al 2019. La 4\/4 incarna e celebra lo spirito dell\u2019azienda, tanto da diventare una vera e propria musa ispiratrice per la casa automobilistica. Il suo nome particolare deriva dal numero delle ruote, 4 appunto, unito al numero dei cilindri, l\u2019altro 4. Una sigla sicuramente originale che stup\u00ec i presenti al Salone dell\u2019Automobile di Londra, quando venne presentata nel 1936.<\/p>\n<p>Successivamente, nel 1959 il fondatore dell\u2019azienda mor\u00ec e venne sostituito nella direzione dal figlio Charles che continu\u00f2 la produzione dei pochi ma tanto apprezzati modelli. Nel suo proseguimento dell&#8217;operato del padre arrivo poi, nel 1968, alla realizzazione di un ulteriore modello, la <strong>Morgan Plus 8<\/strong>, che rimase in produzione fino al 2004.<\/p>\n<p>Durante gli <strong>anni 2000<\/strong> vennero introdotti <strong>altri modelli<\/strong>: la <strong>Aero 8<\/strong>, una potente vettura sportiva dotata di un potente motore V8 da 4.4 di cilindrata a marchio BMW e di un telaio in alluminio; nel 2005 vede la luce il progetto Aeromax, con sole 100 vetture prodotte dalle notevoli prestazioni, una potenza di 367 CV e una velocit\u00e0 massima di 270 km\/h.<\/p>\n<p>Nella sua lunga storia c\u2019\u00e8 spazio anche per la <strong>sperimentazione<\/strong> e l\u2019<strong>innovazione<\/strong> e, arrivando al 2008, la Morgan presenta al Salone dell\u2019Auto di Ginevra un prototipo, la LIFEcar, dotato di motore ad idrogeno e di un\u2019accattivante carrozzeria in metallo lucido dal sapore nostalgico e futuristico insieme. Oltre a lei, arriva anche la nuova Aero GT, realizzata in soli 8 esemplari. L\u2019anno successivo, nel 2009, al Concorso d\u2019eleganza Villa d\u2019Este \u00e8 stata presentata la Aero SuperSport, una vettura creata per celebrare il centenario della casa e in grado di fondere l\u2019avvolgente stile retr\u00f2 e le forme tradizionali con finiture e dettagli pi\u00f9 moderni, come la calandra e i dettagli in metallo cromato.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"La_nuova_vita_di_una_marca_iconica\"><strong>La nuova vita di una marca iconica<\/strong><\/span><\/h3>\n<p>Cos\u00ec, mentre le <strong>motorizzazioni<\/strong> e le <strong>prestazioni cambiano<\/strong>, il <strong>design rimane quasi lo stesso<\/strong>: linee morbide e gusto retr\u00f2 dei primi del \u2018900 che verranno rispettate anche quando nel 2019 arriver\u00e0 l\u2019acquisizione da parte del gruppo italiano Investindustrial con la gestione del manager Massimo Fumarola. CEO determinato a rispolverare il glamour anni \u201930 della Morgan e a riportarlo in auge, con piccoli rinnovamenti per esaltare una vettura dal fascino intramontabile.<\/p>\n<p>Ad oggi i modelli in produzione sono tre: la <strong>Plus Four<\/strong>, la <strong>Plus Six<\/strong> e la <strong>Super 3<\/strong>, l\u2019iconico veicolo a tre ruote che lanci\u00f2 il marchio e che lo ha reso famoso in tutto il mondo. Un fulgido esempio, insomma, di coerenza e fedelt\u00e0 alle proprie origini che si rinnova nella produzione attuale, contando anche sulla collaborazione con BMW che si occupa della parte meccanica del famoso marchio inglese.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Presente_e_futuro_della_Morgan\"><strong>Presente e futuro della Morgan<\/strong><\/span><\/h2>\n<p>Le auto cosiddette instant classic della Morgan, dal sapore senza tempo, nostalgiche e poetiche nelle loro linee morbide e di gran classe, sono amate in tutto il mondo per il loro fascino intramontabile e il loro carattere deciso, in grado di resistere allo scorrere del tempo e delle mode. Vediamo pi\u00f9 da vicino i tre modelli\u00a0 oggi in produzione<strong>: Super 3<\/strong>, <strong>Plus Four<\/strong> e <strong>Plus Six<\/strong>.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Morgan_Super_3\"><strong>Morgan Super 3<\/strong><\/span><\/h3>\n<p>La <strong>Super 3<\/strong>, che ha sostituito la Three Wheeler e che oggi monta un motore a marchio Ford, pur essendo uno tra i <a href=\"https:\/\/www.virgilio.it\/motori\/moto\/le-migliori-moto-tre-ruote-sul-mercato\/213325\/#MORGAN_SUPER_3\">veicoli a tre ruote<\/a> pi\u00f9 amato, non ha proprio niente a che vedere con le moderne vetture ma \u00e8 un concentrato di gusto retr\u00f2 dove si guida all\u2019interno di un <strong>piccolo abitacolo<\/strong>, indossando un casco, anche in due. Un\u2019emozione elettrizzante, un tuffo nel passato con questo veicolo lungo 3,53 metri, dal peso di 650 kg, che monta un <strong>motore da 1.5 di cilindrata, a tre cilindri e 118 CV<\/strong>, prodotto dalla Ford, unito ad un cambio manuale a 5 rapporti, derivato dalla Mazda MX-5, che d\u00e0 brio e velocit\u00e0 alla vettura. Un vero bolide del passato per divertirsi nel presente e, perch\u00e9 no, anche nel futuro.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Morgan_Plus_Four_e_Morgan_Plus_Six\"><strong>Morgan Plus Four e Morgan Plus Six<\/strong><\/span><\/h3>\n<p>La <strong>Morgan Plus Four<\/strong> e la <strong>Morgan Plus Six<\/strong> possono essere definite le sorelle della produzione della Morgan. Condividono infatti lo <strong>stesso telaio in alluminio<\/strong>, pur con motorizzazioni diverse, e lo stesso stile iconico e rimasto quasi immutato da decenni: fanali tondeggianti, passaruota ampi e caratteristici, la vistosa griglia per raffreddare il motore e un equipaggiamento ridotto all\u2019osso con la coda dell\u2019auto che ha un vano apposito per accogliere la ruota di scorta. L\u2019elettronica presente \u00e8 al minimo indispensabile e anche la capote in tela si manovra solamente a mano. Uno stile di altri tempi, insomma, ricco di fascino che ammalia ancora oggi, nell\u2019epoca dell\u2019ipertecnologico.<\/p>\n<p><strong>Morgan Plus Four<\/strong>, con <strong>motore BMW a quattro cilindri<\/strong> con trasmissione manuale, disponibile anche con il cambio automatico, raggiunge una <strong>velocit\u00e0 massima di 240 km\/h<\/strong> e l\u2019incredibile accelerazione da 0 a 100 km\/h in 5,2 secondi per la versione manuale e di 4,8 per quella automatica. Tempi di tutto rispetto per una &#8220;nonnina&#8221; ancora scattante e travolgente. Il tutto per un peso light di circa 1.000 kg. La sorella maggiore, la <strong>Morgan Plus Six<\/strong> pu\u00f2 contare invece su <strong>motore BMW da 3.0 di cilindrata turbo a sei cilindri<\/strong>, anche lei con un peso leggero di circa 1.100 kg con cambio solo automatico.<\/p>\n<p>Gioiellini non proprio per tutte le tasche con cifre a partire <strong>da 60.000 euro per la Super 3<\/strong>, intorno ai <strong>93.000 euro per la Morgan Plus Four<\/strong> con cambio manuale e <strong>oltre i 100.000 mila euro per la Morgan Plus Six<\/strong>. Se invece si preferisce orientarsi su una <strong>vettura usata<\/strong>, sono rare e chi la possiede la tiene ben stretta ma \u00e8 ancora possibile trovarne qualcuna, i prezzi partono <strong>da circa 30.000 euro<\/strong>.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Qualche_curiosita_sul_marchio_Morgan\"><strong>Qualche curiosit\u00e0 sul marchio Morgan<\/strong><\/span><\/h2>\n<p><strong>Qualche ultima curiosit\u00e0<\/strong> sull\u2019iconica casa automobilistica britannica che ci far\u00e0 amare ancora di pi\u00f9 queste vetture, molto apprezzate soprattutto negli Stati Uniti e con una <strong>produzione di 800 vetture all\u2019anno<\/strong>:<\/p>\n<ul>\n<li><strong>non esiste<\/strong> una vera e propria <strong>catena di montaggio<\/strong> ma sono le varie maestranze che girano attorno alla vettura per la sua costruzione, che viene spostata via via nei vari reparti;<\/li>\n<li>tutta <strong>la produzione interna \u00e8 artigianale<\/strong>, realizzata su misura come fosse un vestito, mentre le lavorazioni automatiche sono fatte esternamente;<\/li>\n<li>Morgan sta pensando al futuro con la realizzazione di una <strong>vettura alimentata con un motore elettrico<\/strong>, in vista nel prossimo futuro dello stop alla produzione di motori termici.<\/li>\n<li>uno degli ultimi modelli proposti, rigorosamente in edizione limitata, ha visto la collaborazione con l\u2019azienda italiana di design automobilistico Pininfarina. \u00c8 nata cos\u00ec la <a href=\"https:\/\/www.virgilio.it\/motori\/auto\/midsummer-pininfarina-morgan\/225330\/\">Morgan Midsummer<\/a>, realizzata quest\u2019anno in soli 50 esemplari che stupisce per la sua classe d\u2019altri tempi e la sua ricercatezza contemporanea.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"Il marchio Morgan \u00e8 noto fin dai primi del Novecento per la produzione artigianale delle sue auto","protected":false},"author":183220870,"featured_media":248393,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"amp_status":"","footnotes":""},"categories":[420889857],"tags":[420890811],"coauthors":[420891365,420891366],"class_list":{"0":"post-77471","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-auto","8":"tag-auto-depoca","9":"iol-hentry"},"jetpack_featured_media_url":"https:\/\/www.virgilio.it\/motori\/wp-content\/uploads\/sites\/4\/2016\/02\/Morgan-auto-depoca-storia-e-curiosita-del-marchio.jpg","_links":{"self":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/77471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/users\/183220870"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/comments?post=77471"}],"version-history":[{"count":20,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/77471\/revisions"}],"predecessor-version":[{"id":267075,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/posts\/77471\/revisions\/267075"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media\/248393"}],"wp:attachment":[{"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/media?parent=77471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/categories?post=77471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/tags?post=77471"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.virgilio.it\/motori\/wp-json\/wp\/v2\/coauthors?post=77471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}